{"id":17075,"date":"2022-03-09T08:00:00","date_gmt":"2022-03-09T08:00:00","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=17075"},"modified":"2024-02-21T09:45:58","modified_gmt":"2024-02-21T09:45:58","slug":"plazo-para-pagar-plusvalia-municipal","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/plazo-para-pagar-plusvalia-municipal\/","title":{"rendered":"\u00bfCu\u00e1l es el plazo para pagar plusval\u00eda municipal?"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">Si has <strong>vendido un piso<\/strong> recientemente o has aceptado una herencia, tendr\u00e1s que <a href=\"https:\/\/housfy.com\/vender-pisos\/guias\/post\/plusvalia\">pagar el impuesto de plusval\u00eda municipal<\/a>. Esta tasa grava el incremento del valor del terreno, y no debemos confundirlo con el IRPF. Cuando los vendedores o herederos se encuentran en esta situaci\u00f3n, acostumbran a tener bastantes dudas respecto a este impuesto. En el art\u00edculo de hoy veremos cu\u00e1l es el plazo para pagar plusval\u00eda municipal y cu\u00e1nto tendr\u00e1s que pagar.<\/span><\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-33\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_33 module_id_33  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"33\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfCu\u00e1nto vale mi casa? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfCu\u00e1nto vale mi casa?<\/h3><h4 class=\"hustle-subtitle\">Realiza la valoraci\u00f3n online y gratuita de tu vivienda en pocos minutos<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/valoracion-piso?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_valoracion_blog&#038;utm_term=valoracion_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">VALORAR VIVIENDA GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es la plusval\u00eda municipal?<\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">El<strong> impuesto de plusval\u00eda o el impuesto sobre el incremento del valor de los terrenos de\u00a0 naturaleza urbana (IIVTNU)<\/strong> grava el incremento del valor del terreno desde la compra, herencia o la venta. Este tributo lo recauda el ayuntamiento del municipio en el que te encuentres, esto repercutir\u00e1 en cu\u00e1nto pagar\u00e1s, ya que el Ayuntamiento es el que decide el tipo impositivo que se aplicar\u00e1, que no puede ser superior al 30%.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">El impuesto de Plusval\u00eda Municipal tendr\u00e1s que pagarlo aquellos que hayan vendido, heredado o recibido una donaci\u00f3n de un inmueble. M\u00e1s adelante veremos c\u00f3mo el motivo de la transacci\u00f3n afecta al plazo para pagar este impuesto. Pero antes de adentrarnos en ese tema, veamos <strong>c\u00f3mo puedes <a href=\"https:\/\/housfy.com\/vender-pisos\/calculadora-plusvalia-municipal\">calcular la plusval\u00eda municipal<\/a>.<\/strong><\/span><\/p>\n\n\n<p>[irp posts=\u00bb14280&#8243; name=\u00bb\u00bfC\u00f3mo repartir herencia piso si una parte no quiere vender?\u00bb]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Plazo para pagar plusval\u00eda municipal y saber calcularlo<\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Como hemos dicho al principio, <strong>el pago del <a href=\"https:\/\/housfy.com\/vender-pisos\/guias\/post\/irpf-venta-vivienda\">IRPF<\/a> no es lo mismo que el impuesto de plusval\u00eda<\/strong>, el primero es f\u00e1cil de calcular a trav\u00e9s de la ganancia patrimonial y viendo el porcentaje que tendr\u00edas que aplicar. Cuando hablamos de plusval\u00eda, la cosa se complica y es que para saber cu\u00e1nto tienes que pagar necesitar\u00e1s conocer unos cuantos datos del inmueble:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Valor de transmisi\u00f3n de la vivienda. <\/b><span style=\"font-weight: 400;\">Se refiere al precio de venta de esta.<\/span><\/li>\n\n\n\n<li><b>Valor de adquisici\u00f3n de la vivienda. <\/b><span style=\"font-weight: 400;\">En este caso, se trata del precio que se pag\u00f3 cuando se adquiri\u00f3 el inmueble.<\/span><\/li>\n\n\n\n<li><b><a href=\"https:\/\/housfy.com\/vender-pisos\/tasacion-referencia-catastral\">Valor catastral<\/a><\/b><span style=\"font-weight: 400;\">. Podr\u00e1s encontrar este dato en el \u00faltimo recibo del IBI o a trav\u00e9s del catastro, ya sea a trav\u00e9s de la Sede Electr\u00f3nica o a trav\u00e9s de las oficinas.&nbsp;<\/span><\/li>\n<\/ul>\n\n\n\n<p>A modo de ejemplo, y para que puedas hacerte una idea, te mostramos los coeficientes de incremento para calcular la plusval\u00eda en la ciudad de Barcelona y Madrid.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Coeficiente para calcular plusval\u00eda en Barcelona<\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">C\u00f3mo dec\u00edamos anteriormente, <strong>cada Ayuntamiento decide un coeficiente<\/strong> que tendremos que multiplicar por la base imponible de la plusval\u00eda municipal, es decir, multiplicar este coeficiente por el resultado que nos de el c\u00e1lculo de la plusval\u00eda a trav\u00e9s de una de las dos f\u00f3rmulas que hay para calcularla y que cada contribuyente puede escoger, seg\u00fan le beneficie m\u00e1s. En el caso de Barcelona, el coeficiente escogido es un porcentaje del 30%.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Coeficiente para calcular plusval\u00eda en Madrid<\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Por su parte, en Madrid el <\/span><b>coeficiente escogido es del 29%<\/b><span style=\"font-weight: 400;\">, el cual se tendr\u00e1 que multiplicar por el resultado final que obtengamos tras calcular la plusval\u00eda a trav\u00e9s de una de los dos m\u00e9todos que el Gobierno indica tras la aprobaci\u00f3n del Decreto-Ley del 10 de noviembre de 2021.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Periodos y coeficientes de incremento para calcular plusval\u00eda municipal<\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Por lo que respecta a los coeficientes de incremento para calcular la plusval\u00eda municipal dependiendo del tiempo en el que el vendedor fue propietario de la vivienda, el Ministerio de Haciend establece los m\u00e1ximos siguientes:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Menos de un a\u00f1o = 0,14<\/span><\/li>\n\n\n\n<li>1 a\u00f1o = 0,13<\/li>\n\n\n\n<li>2 a\u00f1os = 0,15<\/li>\n\n\n\n<li>3 a\u00f1os = 0,16<\/li>\n\n\n\n<li>4 a\u00f1os = 0,17<\/li>\n\n\n\n<li>5 a\u00f1os = 0,17<\/li>\n\n\n\n<li>6 a\u00f1os = 0,16<\/li>\n\n\n\n<li>7 a\u00f1os = 0,12<\/li>\n\n\n\n<li>8 a\u00f1os = 0,10<\/li>\n\n\n\n<li>9 a\u00f1os = 0,09<\/li>\n\n\n\n<li>10 a\u00f1os = 0,08<\/li>\n\n\n\n<li>11 a\u00f1os = 0,08<\/li>\n\n\n\n<li>12 a\u00f1os = 0,08<\/li>\n\n\n\n<li>13 a\u00f1os = 0,08<\/li>\n\n\n\n<li>14 a\u00f1os = 0,10<\/li>\n\n\n\n<li>15 a\u00f1os = 0,12<\/li>\n\n\n\n<li>16 a\u00f1os = 0,16<\/li>\n\n\n\n<li>17 a\u00f1os = 0,20<\/li>\n\n\n\n<li>18 a\u00f1os = 0,26<\/li>\n\n\n\n<li>19 a\u00f1os = 0,36<\/li>\n\n\n\n<li>20 a\u00f1os = 0,45<\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-size: 1.28571rem;\">\u00bfCu\u00e1l es el plazo para pagar plusval\u00eda municipal?<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Ahora que ya sabemos qu\u00e9 es y c\u00f3mo calcularlo, veamos cu\u00e1l es el plazo para pagar plusval\u00eda municipal.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Si has vendido un piso<\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">En el caso de que hayas vendido un inmueble,<strong> tienes un periodo m\u00e1ximo de 30 d\u00edas h\u00e1biles para pagar el impuesto.<\/strong> Pueden haber algunos cambios respecto al plazo seg\u00fan el municipio en el que residas, as\u00ed que es importante que lo verifiques para que no se te pase el plazo.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">El pago puedes hacerlo de forma presencial o telem\u00e1ticamente, pero ten en cuenta que la segunda forma de pago no est\u00e1 disponible en todas las localidades:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Presencialmente<\/b><span style=\"font-weight: 400;\">. Tendr\u00e1s que dirigirte a las oficinas municipales, obtener la planilla de liquidaci\u00f3n<\/span> <span style=\"font-weight: 400;\">y hacer el pago.<\/span><\/li>\n\n\n\n<li><b>Telem\u00e1ticamente.<\/b><span style=\"font-weight: 400;\"> Desde la misma web, puedes descargarte el formulario de liquidaci\u00f3n y hacer el pago.<\/span><\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2021\/04\/30135749\/spacejoy-YnLJ3rM4VtI-unsplash-700x394.jpg\" alt=\"plazo para pagar plusval\u00eda municipal\" class=\"wp-image-17080\" title=\"- Housfy\"><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Si has heredado una vivienda<\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">En el caso de haber aceptado una herencia, el plazo es distinto,<strong> tienes un periodo de 6 meses desde el fallecimiento<\/strong>, para pagar el impuesto de plusval\u00eda. Existe la opci\u00f3n de <strong>solicitar <\/strong>un aplazamiento de 6 meses m\u00e1s, si lo haces antes de los 5 meses, pero lo m\u00e1s seguro es que te apliquen intereses en el pago.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Plazo para pagar plusval\u00eda municipal y sanciones<\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Es muy importante que pagues el impuesto en el plazo que dicte el ayuntamiento, de lo contrario podr\u00edas ser sancionado con pagar intereses:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>3 meses de retraso:<\/b><span style=\"font-weight: 400;\"> 5% de recargo.<\/span><\/li>\n\n\n\n<li><b>De 3 a 6 meses:<\/b><span style=\"font-weight: 400;\"> 10% de recargo.<\/span><\/li>\n\n\n\n<li><b>De 6 a 12 meses: <\/b><span style=\"font-weight: 400;\">15% de recargo.<\/span><\/li>\n\n\n\n<li><b>M\u00e1s de un a\u00f1o:<\/b><span style=\"font-weight: 400;\"> A partir del 20% de recargo por sanci\u00f3n.&nbsp;<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Estas son las sanciones en caso de que se pague fuera de plazo, pero en el caso de impago podr\u00eda llegar a un 150%.<strong> En este tipo de sanci\u00f3n el recargo oscila entre el 50% al 150%<\/strong>, depender\u00e1 de c\u00f3mo de grave consideran la infracci\u00f3n.&nbsp;<\/span><\/p>\n\n\n\n<p>Si est\u00e1s interesado en <a href=\"https:\/\/housfy.com\/vender-pisos\">poner a la venta tu inmueble<\/a>, no dudes en ponerte en contacto con nuestros expertos inmobiliarios. Estaremos encantados de ayudarte en todo el proceso.<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-33\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_33 module_id_33  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"33\"\r\n\t\t\tdata-render-id=\"1\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfCu\u00e1nto vale mi casa? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfCu\u00e1nto vale mi casa?<\/h3><h4 class=\"hustle-subtitle\">Realiza la valoraci\u00f3n online y gratuita de tu vivienda en pocos minutos<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/valoracion-piso?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_valoracion_blog&#038;utm_term=valoracion_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">VALORAR VIVIENDA GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si has vendido un piso recientemente o has aceptado una herencia, tendr\u00e1s que pagar el impuesto de plusval\u00eda municipal. Esta tasa grava el incremento del valor del terreno, y no debemos confundirlo con el IRPF. Cuando los vendedores o herederos se encuentran en esta situaci\u00f3n, acostumbran a tener bastantes dudas respecto a este impuesto. En el art\u00edculo de hoy veremos cu\u00e1l es el plazo para pagar plusval\u00eda municipal y cu\u00e1nto tendr\u00e1s que pagar. \u00bfQu\u00e9 es la plusval\u00eda municipal? El impuesto de plusval\u00eda o el impuesto sobre el incremento del valor de los terrenos de\u00a0 naturaleza urbana (IIVTNU) grava el incremento <\/p>\n","protected":false},"author":1,"featured_media":28488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-17075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2022\/03\/09091442\/plazo-para-pagar-plusvalia-municipal-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/17075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=17075"}],"version-history":[{"count":28,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/17075\/revisions"}],"predecessor-version":[{"id":54514,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/17075\/revisions\/54514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/28488"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=17075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=17075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=17075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}