{"id":20802,"date":"2021-09-15T07:00:55","date_gmt":"2021-09-15T06:00:55","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=20802"},"modified":"2026-07-23T13:18:12","modified_gmt":"2026-07-23T13:18:12","slug":"housfy-cierra-una-ronda-de-financiacion-de-10-millones-de-euros","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/housfy-cierra-una-ronda-de-financiacion-de-10-millones-de-euros\/","title":{"rendered":"Housfy cierra una ronda de financiaci\u00f3n de 10 millones de euros"},"content":{"rendered":"<p><a href=\"https:\/\/housfy.com\/\"><b>Housfy<\/b><\/a><b>, la plataforma digital de servicios inmobiliarios y del hogar,<\/b><span style=\"font-weight: 400;\"> ha cerrado una <\/span><b>ronda de financiaci\u00f3n de 10 millones de euros<\/b><span style=\"font-weight: 400;\"> cuyo principal objetivo es <\/span><b>invertir en el desarrollo de la plataforma y reforzar la expansi\u00f3n internacional de la compa\u00f1\u00eda<\/b><span style=\"font-weight: 400;\">. En la nueva ronda han participado los fondos <\/span><b>Seaya Ventures, Torch Capital, DN Capital y Cathay Capital<\/b><span style=\"font-weight: 400;\">, a trav\u00e9s de C. Entrepreneurs, que ya participaron en rondas anteriores, a los que se suman <\/span><b>Aldea Ventures y CDTI<\/b><span style=\"font-weight: 400;\"> como novedades de la nueva financiaci\u00f3n.<\/span><\/p>\n<h2><b>Housfy<\/b><b>, la plataforma digital de servicios inmobiliarios y del hogar<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Housfy ha sentado las bases del primer ecosistema online de servicios inmobiliarios y del hogar del sur de Europa. Esta plataforma <\/span><b>permite contratar servicios y realizar cualquier gesti\u00f3n en torno a la vivienda<\/b><span style=\"font-weight: 400;\">: compraventa, gesti\u00f3n hipotecaria, alquileres, reformas, mudanzas, servicios para empresas inmobiliarias, venta directa de vivienda en 24 horas, corredur\u00eda de seguros, suministros y muchos m\u00e1s que ser\u00e1n integrados en los pr\u00f3ximos meses.<\/span><\/p>\n<div id=\"attachment_20805\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-20805\" class=\"wp-image-20805 size-large\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2021\/09\/14160051\/Imagen-App-3-700x467.jpg\" alt=\"plataforma digital housfy servicio cliente\" width=\"700\" height=\"467\" title=\"- Housfy\"><p id=\"caption-attachment-20805\" class=\"wp-caption-text\">Housfy, la plataforma digital de servicios inmobiliarios y del hogar<\/p><\/div>\n<p><span style=\"font-weight: 400;\">La nueva inyecci\u00f3n de capital se destinar\u00e1 tambi\u00e9n a <\/span><b>seguir mejorando la experiencia del cliente<\/b><span style=\"font-weight: 400;\">, simplificando los procesos y acerc\u00e1ndolos a todos los consumidores. Por otro lado, esta ronda tambi\u00e9n servir\u00e1 para <\/span><b>impulsar el negocio a nivel internacional<\/b><span style=\"font-weight: 400;\">, <\/span><b>con Portugal como primer objetivo de la compa\u00f1\u00eda.<\/b><\/p>\n<p>[irp posts=\u00bb17253&#8243; name=\u00bbHousfy se al\u00eda con Santander y ofrecer\u00e1 un servicio de venta de viviendas a sus clientes\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Housfy prev\u00e9 cerrar el ejercicio de 2021 con una <\/span><b>facturaci\u00f3n neta de 15 millones de euros y con un crecimiento del 140% respecto a 2020<\/b><span style=\"font-weight: 400;\">. Actualmente emplea a m\u00e1s de 200 profesionales en sus oficinas del 22@ en Barcelona. Hasta d\u00eda de hoy, Housfy ha vendido cerca de 5.000 viviendas y gestionado m\u00e1s de 2.000 hipotecas como <a href=\"https:\/\/housfy.com\/hipoteca\/broker-hipotecario\"><strong>br\u00f3ker hipotecario<\/strong><\/a> certificado.\u00a0<\/span><\/p>\n<div id=\"attachment_20803\" style=\"width: 710px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-20803\" class=\"wp-image-20803 size-large\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2021\/09\/14155710\/Imagen-CEO-700x467.jpg\" alt=\"Albert Bosch Ceo Housfy Rondaa de financiaci\u00f3n de 10 millones\" width=\"700\" height=\"467\" title=\"- Housfy\"><p id=\"caption-attachment-20803\" class=\"wp-caption-text\">Albert bosch, ceo de housfy<\/p><\/div>\n<p><i><span style=\"font-weight: 400;\">\u201cLa ronda de financiaci\u00f3n nos servir\u00e1 para seguir creciendo e invertir en la experiencia de usuario. No hay tecnolog\u00eda que valga sin una buena experiencia por parte del cliente, ese es nuestro mayor foco ahora mismo. Tenemos un gran reto por delante: simplificar el proceso de los servicios inmobiliarios para que todos los usuarios puedan llevar a cabo cualquier gesti\u00f3n relativa a la vivienda de manera f\u00e1cil y sencilla desde una misma plataforma\u201d<\/span><\/i><span style=\"font-weight: 400;\">, afirma <\/span><b>Albert Bosch, CEO y fundador de Housfy<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>[irp posts=\u00bb2166&#8243; name=\u00bb\u00bfQu\u00e9 diferencia a Housfy de las dem\u00e1s agencias inmobiliarias?\u00bb]<\/p>\n<p><b>Inversores<\/b><\/p>\n<p><b>Seaya Ventures<\/b><span style=\"font-weight: 400;\">, fondo de Venture Capital l\u00edder en Europa y Am\u00e9rica Latina, contin\u00faa con su apuesta por el mercado proptech. Entre el resto de inversores se incluye el reconocido fondo de inversi\u00f3n brit\u00e1nico <\/span><b>DN Capital<\/b><span style=\"font-weight: 400;\">, que fue inversor de Purplebricks, la proptech que comercializa m\u00e1s de 50.000 inmuebles en el Reino Unido y que cotiza en bolsa. Tambi\u00e9n destaca <\/span><b>Torch Capital<\/b><span style=\"font-weight: 400;\">, un fondo de EE. UU. que invirti\u00f3 en la proptech Compass, valorada en m\u00e1s de 4 billones de d\u00f3lares. La operaci\u00f3n ha contado tambi\u00e9n con <\/span><b>Cathay Capital a trav\u00e9s de C. Entrepreneurs<\/b><span style=\"font-weight: 400;\">. Adem\u00e1s, desde ahora, <\/span><b>Aldea Capital<\/b><span style=\"font-weight: 400;\"> y <\/span><b>CDTI<\/b><span style=\"font-weight: 400;\"> (Centro para el Desarrollo Tecnol\u00f3gico Industrial) se suman al accionariado mediante la \u00faltima ronda de financiaci\u00f3n. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Housfy, la plataforma digital de servicios inmobiliarios y del hogar, ha cerrado una ronda de financiaci\u00f3n de 10 millones de euros cuyo principal objetivo es invertir en el desarrollo de la plataforma y reforzar la expansi\u00f3n internacional de la compa\u00f1\u00eda. En la nueva ronda han participado los fondos Seaya Ventures, Torch Capital, DN Capital y Cathay Capital, a trav\u00e9s de C. Entrepreneurs, que ya participaron en rondas anteriores, a los que se suman Aldea Ventures y CDTI como novedades de la nueva financiaci\u00f3n. Housfy, la plataforma digital de servicios inmobiliarios y del hogar Housfy ha sentado las bases del primer <\/p>\n","protected":false},"author":60,"featured_media":20804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,134],"tags":[],"class_list":["post-20802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2021\/09\/14155937\/Imagen-App-1-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/20802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=20802"}],"version-history":[{"count":8,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/20802\/revisions"}],"predecessor-version":[{"id":32029,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/20802\/revisions\/32029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/20804"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=20802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=20802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=20802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}