{"id":31061,"date":"2022-04-19T14:48:47","date_gmt":"2022-04-19T14:48:47","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=31061"},"modified":"2026-07-23T13:24:19","modified_gmt":"2026-07-23T13:24:19","slug":"declarar-criptomonedas-en-la-renta","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/declarar-criptomonedas-en-la-renta\/","title":{"rendered":"Declarar criptomonedas en la Renta 2021: c\u00f3mo se hace"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El mundo de las criptomonedas lleva bastante tiempo en crecimiento constante, sobre todo despu\u00e9s de la pandemia. Cada vez m\u00e1s gente opta por ellas, siendo una de las opciones para invertir y generar ingresos, igual que hace mucha gente al comprar y <strong><a href=\"https:\/\/housfy.com\/vender-pisos\">vender<\/a><\/strong> inmuebles. Sin embargo, es cierto que muchas de estas personas tambi\u00e9n se encuentran indecisas a la hora de declarar criptomonedas en la Renta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si t\u00fa tambi\u00e9n dudas en c\u00f3mo <strong>declarar criptomonedas para justificarlo a Hacienda<\/strong>, qu\u00e9date en este post porque te lo vamos a explicar.<\/p>\n\n\n<div class=\"housfy-cta-wrapper\"><a class=\"housfy-cta\" href=\"https:\/\/housfy.com\/?utm_source=traffic_CTAButton_blog&amp;utm_medium=CTAButton&amp;utm_campaign=CTAButton_valora_tu_piso_blog&amp;utm_content=vende_tu_piso_CTAButton_blog\" title=\"Vende tu piso con Housfy\">Vende tu piso con Housfy<\/a><\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 son las criptomonedas?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>criptomonedas <\/strong>son activos digitales que hacen uso de un cifrado criptogr\u00e1fico para garantizar su titularidad y controlar la creaci\u00f3n de unidades adicionales (en otras palabras, evitar que alguien haga copias de las mismas). Se debe remarcar que son monedas digitales, es decir, no existen de forma f\u00edsica, y se almacenan en una cartera digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera criptomoneda existente fue la archiconocida Bitcoin en el 2009. M\u00e1s tarde aparecieron otras tambi\u00e9n populares como Litecoin, Ethereum o Binance (BNB).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a las criptomonedas en Espa\u00f1a, est\u00e1n autorizadas como medio de pago legal desde 2015.<\/p>\n\n\n<p>[irp posts=\u00bb16867&#8243; name=\u00bbRenta 2021: \u00bfcu\u00e1nto desgrava la hipoteca?\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo se puede declarar criptomonedas en la renta?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lo primero que debes saber es que si est\u00e1s trabajando con criptomonedas pero tus ingresos no llegan a los 1.000 \u20ac, no tienes la obligaci\u00f3n de presentarlo en la <strong><a href=\"https:\/\/housfy.com\/blog\/que-significa-la-clave-de-titularidad-de-la-vivienda\/\">Declaraci\u00f3n de la Renta<\/a><\/strong> para justificarlo a Hacienda. Si ganaras m\u00e1s de esa cifra, entonces s\u00ed deber\u00edas declararlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si se incluyen criptomonedas en la declaraci\u00f3n de la renta, tendr\u00e1s que incluir de forma obligatoria las ganancias que obtengas. Pero si, al contrario, tienes p\u00e9rdidas, no hace falta que las declares, es totalmente opcional. Sin embargo, se recomienda hacerlo porque as\u00ed existe la posibilidad de compensarlas en los cuatro ejercicios siguientes de la renta con las ganancias en concepto de transmisi\u00f3n de otros elementos patrimoniales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Administraci\u00f3n p\u00fablica ha incluido una <strong>casilla para las monedas virtuales en la declaraci\u00f3n de la renta<\/strong> (casilla 1.626) <strong>y en el patrimonio<\/strong> (casilla 47). La cantidad obtenida por rendimiento se debe declarar en la base imponible del ahorro como ganancia o como p\u00e9rdida patrimonial:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hasta 6.000 \u20ac: 19 %<\/li>\n\n\n\n<li>De 6.000 \u20ac a 50.000 \u20ac: 21 %<\/li>\n\n\n\n<li>De 50.000 \u20ac a 200.000 \u20ac: 23 %<\/li>\n\n\n\n<li>M\u00e1s de 200.000 \u20ac: 26 %<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Reflejo de las criptomonedas en la declaraci\u00f3n de la renta<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La renta en torno a las criptomonedas se estructura en cuatro partes diferenciadas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Ganancias y p\u00e9rdidas por transmisi\u00f3n. <\/strong>En este apartado entrar\u00eda toda la actividad m\u00e1s com\u00fan en el mundo de las <em>crypto <\/em>(compraventa o intercambio).<\/li>\n\n\n\n<li><strong>Rendimientos. <\/strong>Aqu\u00ed entra el apartado de las plataformas a las cuales enviamos criptomonedas y ellas nos generan un rendimiento. Un ejemplo de ello son las plataformas binance, en las que guardamos las monedas <em>crypto <\/em>y podemos ver la evoluci\u00f3n de los valores de las mismas.<\/li>\n\n\n\n<li><strong>Ganancias y p\u00e9rdidas sin transmisi\u00f3n. <\/strong>Airdrops, referidos, premios, monedas obtenidas sin comprarlas de forma directa, etc.<\/li>\n\n\n\n<li><strong>Actividad econ\u00f3mica. <\/strong>Se refiere a la actividad de miner\u00eda, trading, compraventa de criptomonedas para terceros, etc.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2022\/08\/11100414\/declarar-criptomonedas-en-la-Renta.jpg\" alt=\"C\u00f3mo declarar criptomonedas en la Renta\" class=\"wp-image-39177\" title=\"- Housfy\"><figcaption class=\"wp-element-caption\">C\u00f3mo declarar criptomonedas en la renta<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Impuesto sobre el Patrimonio y c\u00f3mo afecta a las criptomonedas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es un impuesto complementario que depende de cada comunidad aut\u00f3noma. Se presenta en la renta con el <strong>Modelo 714<\/strong>. Lo que nos interesa de este apartado es que, si la cantidad que tenemos de criptomonedas supera una cifra determinada, hay que declararlo y se aplica el Impuesto sobre el Patrimonio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Novedades sobre las criptomonedas en 2022<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La aprobaci\u00f3n de la Ley 11\/2021, de 9 de julio, de medidas de prevenci\u00f3n y lucha contra el fraude fiscal especifica a qu\u00e9 est\u00e1n obligados los contribuyentes en relaci\u00f3n a las criptomonedas de cara a su declaraci\u00f3n. Como novedad, hay <strong>dos obligaciones nuevas<\/strong>:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Obligaci\u00f3n, para las empresas que gestionan criptomonedas, de informar de cada uno de sus saldos y de la identidad de sus titulares.<\/li>\n\n\n\n<li>Obligaci\u00f3n que marca que los exchanges o intercambios que cumplan con lo que dicta el texto de la ley, deben informar de los domicilios, la identificaci\u00f3n fiscal, el precio y la fecha de las operaciones llevadas a cabo.<\/li>\n<\/ol>\n\n\n<p>[irp posts=\u00bb26796&#8243; name=\u00bb\u00bfCu\u00e1nto dinero se puede transferir sin declarar a Hacienda?\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Multas por no declarar las criptomonedas en Espa\u00f1a<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los riesgos fiscales de las crypto y sus medidas, seg\u00fan el Plan Anual de Control Tributario y Aduanero, son estos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Agencia Tributaria podr\u00eda sancionar en caso de ocultar criptomonedas en el Modelo 720.<\/li>\n\n\n\n<li>Sobre la cuant\u00eda de las multas, pueden ser de 5.000 \u20ac por cada dato o conjunto de datos que no se declaren.<\/li>\n\n\n\n<li>Cuando la omisi\u00f3n de datos es parcial, falsa o inexacta, la sanci\u00f3n ya parte de los 10.000 \u20ac.&nbsp;<\/li>\n\n\n\n<li>Si el contribuyente se olvida de incluir estos activos, puede presentar voluntariamente una declaraci\u00f3n complementaria siempre que las operaciones con los mismos no superen el valor de 1.500 \u20ac. Si se pasa de este l\u00edmite, se impone una multa de 100 \u20ac.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya conoces el funcionamiento de declarar las criptomonedas en la Renta, no tienes que preocuparte de tener ning\u00fan fallo este a\u00f1o la hora de comunicarlo a Hacienda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mundo de las criptomonedas lleva bastante tiempo en crecimiento constante, sobre todo despu\u00e9s de la pandemia. Cada vez m\u00e1s gente opta por ellas, siendo una de las opciones para invertir y generar ingresos, igual que hace mucha gente al comprar y vender inmuebles. Sin embargo, es cierto que muchas de estas personas tambi\u00e9n se encuentran indecisas a la hora de declarar criptomonedas en la Renta. Si t\u00fa tambi\u00e9n dudas en c\u00f3mo declarar criptomonedas para justificarlo a Hacienda, qu\u00e9date en este post porque te lo vamos a explicar. \u00bfQu\u00e9 son las criptomonedas? Las criptomonedas son activos digitales que hacen uso <\/p>\n","protected":false},"author":62,"featured_media":31062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,123],"tags":[],"class_list":["post-31061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-hipoteca","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2022\/04\/14153526\/Declarar-criptomonedas-en-la-Renta-2021-como-se-hace-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/31061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=31061"}],"version-history":[{"count":13,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/31061\/revisions"}],"predecessor-version":[{"id":42662,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/31061\/revisions\/42662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/31062"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=31061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=31061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=31061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}