{"id":34969,"date":"2022-05-31T10:14:26","date_gmt":"2022-05-31T10:14:26","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=34969"},"modified":"2025-03-11T09:52:59","modified_gmt":"2025-03-11T09:52:59","slug":"como-reclamar-el-impuesto-de-plusvalia-municipal","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/como-reclamar-el-impuesto-de-plusvalia-municipal\/","title":{"rendered":"\u00bfC\u00f3mo reclamar el impuesto de plusval\u00eda municipal?"},"content":{"rendered":"\n<p>En una <strong>operaci\u00f3n de compraventa <\/strong>se realizan muchas acciones, desde el momento de <a href=\"https:\/\/housfy.com\/vender-pisos\"><strong>vender un piso<\/strong><\/a> hasta la firma y entrega de llaves. Pero no hay que olvidar que este procedimiento tambi\u00e9n requieren hacer el pago de ciertos tributos. C\u00f3mo es el <strong>impuesto de plusval\u00eda municipal<\/strong>. Despu\u00e9s de los \u00faltimos y lo dictaminado por el Tribunal Constitucional, es normal que te preguntes \u00bfTengo que pagarlo? Si lo he hecho, \u00bfC\u00f3mo solicito la devoluci\u00f3n plusval\u00eda municipal? A continuaci\u00f3n, te despejamos todas las dudas que tengas al respecto.<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-32\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_32 module_id_32  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"32\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"Vende tu casa consiguiendo m\u00e1s por menos popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">Vende tu casa consiguiendo m\u00e1s por menos<\/h3><h4 class=\"hustle-subtitle\">Pagar mucho por recibir poco es del pasado<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_vender_inmueble_blog&#038;utm_term=vender_inmueble_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">INF\u00d3RMATE GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Impuesto de plusval\u00eda municipal&nbsp;<\/h2>\n\n\n\n<p>Lo primero que hay que aclarar es \u00bfqu\u00e9 es el <a href=\"https:\/\/housfy.com\/vender-pisos\/guias\/post\/plusvalia\"><strong>impuesto de plusval\u00eda municipal<\/strong><\/a>? Esta recaudaci\u00f3n fiscal es el Impuesto sobre el Incremento del Valor de los Terrenos de Naturaleza Urbana. Los ayuntamientos son los encargados del <strong><a href=\"https:\/\/housfy.com\/vender-pisos\/calculadora-plusvalia-municipal\">c\u00e1lculo de la plusval\u00eda municipal<\/a> <\/strong>y de su cobro cuando se dona, hereda o al vender una casa.<\/p>\n\n\n\n<p>Este tributo grava el<strong> incremento del valor del suelo<\/strong> durante los a\u00f1os de posesi\u00f3n y hasta su transmisi\u00f3n. Por lo tanto, entre cuantos m\u00e1s a\u00f1os hayan pasado, mayor ser\u00e1 el porcentaje que se deba pagar. En definitiva, se trata de la diferencia positiva entre su valor de compra y su valor de venta.<\/p>\n\n\n\n<p>La plusval\u00eda municipal se paga cuando una persona <strong>vende, permuta, dona o hereda una propiedad<\/strong>. En las transmisiones gratuitas, donaci\u00f3n y sucesi\u00f3n, el coste lo afronta quien adquiere el terreno y tendr\u00e1n hasta 6 meses para efectuar el pago. En cambio, en el caso de compraventa quien se deber\u00e1 hacer cargo es la parte vendedora, y lo tendr\u00e1 que hacer en los 30 siguientes d\u00edas h\u00e1biles despu\u00e9s de la fecha de venta o donaci\u00f3n. Sin embargo, existen algunos casos en los que se est\u00e1 <a href=\"https:\/\/housfy.com\/blog\/quien-esta-exento-de-pagar-el-impuesto-de-plusvalia-municipal\/\"><strong>exento de pagar la plusval\u00eda municipal<\/strong><\/a>.&nbsp;<\/p>\n\n\n<p>[irp posts=\u00bb58540&#8243; name=\u00bbAs\u00ed es c\u00f3mo puedes fraccionar el pago de la plusval\u00eda\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sentencia del Tribunal Constitucional<\/h2>\n\n\n\n<p>Desde hace varios a\u00f1os el Tribunal Constitucional ya se pronunci\u00f3 sobre la plusval\u00eda municipal. En la sentencia del 2018, el Tribunal Supremo declar\u00f3 que este impuesto solo <strong>deber\u00e1 de ser pagado en el caso de que haya habido ganancias<\/strong> en la operaci\u00f3n. Es decir, cuando el precio de venta del inmueble supera al precio de compra.<\/p>\n\n\n\n<p>Pero en la sentencia m\u00e1s reciente, la 182\/2021 dictamin\u00f3 la anulaci\u00f3n de la plusval\u00eda. Una de las razones fue por como se calculaba con par\u00e1metros objetivos del Impuesto sobre el Incremento del Valor de los Terrenos de Naturaleza Urbanos que no demuestran realmente la cuant\u00eda de la plusval\u00eda obtenida con la venta del inmueble, asaltando as\u00ed el principio de \u201ccapacidad econ\u00f3mica\u201d recogido en el art\u00edculo 30 de la Constituci\u00f3n Espa\u00f1ola.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQui\u00e9n puede reclamar la plusval\u00eda municipal?<\/h2>\n\n\n\n<p>La pregunta m\u00e1s interesante, a quien afecta o quien puede reclamar el coste de este impuesto. Si vendiste tu propiedad, o la recibiste en donaci\u00f3n o herencia, podr\u00e1s reclamar la totalidad de lo pagado por el impuesto de plusval\u00eda municipal, en los<strong> siguientes supuestos<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si <strong>iniciaste una<\/strong> <strong>reclamaci\u00f3n <\/strong>del impuesto de plusval\u00eda antes de la \u00faltima sentencia del Tribunal Constitucional, no recibiste respuesta, y a\u00fan tienes el procedimiento pendiente.<\/li>\n\n\n\n<li>Si tuviste que <strong>liquidar el impuesto<\/strong> entre el d\u00eda 26 de octubre de 2021 y el 9 de noviembre de ese mismo a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<p>Por lo que teniendo en cuenta esta informaci\u00f3n, el Tribunal Constitucional ha limitado el alcance y <strong>rechaza situaciones anteriores al 26 de octubre de 2021<\/strong>, con efecto retroactivo.<\/p>\n\n\n\n<p>En el supuesto de autoliquidaciones, se limita a quienes las hubiera impugnado antes de distarse la sentencia. Es decir, \u00fanicamente podr\u00edan tramitarse las reclamaciones de este impuesto que se hubieran planteado antes de la fecha de sentencia.&nbsp;<\/p>\n\n\n\n<p>Por consiguiente, a partir de ese momento los <strong>Ayuntamientos ya no podr\u00e1n cobrar este impuesto<\/strong>.&nbsp;<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe hidef\" id=\"WYL_UTwmcBbdVcw\"><div id=\"lyte_UTwmcBbdVcw\" data-src=\"https:\/\/housfy.com\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FUTwmcBbdVcw%2Fmaxresdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/UTwmcBbdVcw\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/housfy.com\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FUTwmcBbdVcw%2F0.jpg\" alt=\"- Housfy\" width=\"853\" height=\"460\" title=\"- Housfy\"><br \/>Ver este v\u00eddeo en YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<h2 class=\"wp-block-heading\">Requisitos para reclamar plusval\u00eda municipal<\/h2>\n\n\n\n<p>De manera que si te encuentras en una de las situaciones anteriores, podr\u00e1s <strong>reclamar la devoluci\u00f3n de la plusval\u00eda municipal<\/strong>. Lo primero que debes saber es si <strong>cumples con requisitos<\/strong> para iniciar el tr\u00e1mite:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>No haber obtenido ganancias en la venta del inmueble.<\/li>\n\n\n\n<li>No haberlo obtenido en donaci\u00f3n, herencia, embargo o daci\u00f3n en pago.<\/li>\n\n\n\n<li>Que no haya pasado m\u00e1s de un mes desde que se hizo la liquidaci\u00f3n.<\/li>\n\n\n\n<li>Si se hizo una autoliquidaci\u00f3n, el plazo para solicitar la devoluci\u00f3n es de hasta cuatro a\u00f1os.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Tr\u00e1mites a realizar para reclamar plusval\u00eda&nbsp;<\/h2>\n\n\n\n<p>Una vez te hayas cerciorado que cumples con las condiciones necesarias, podr\u00e1s comenzar el recurso. Te indicamos los pasos a seguir:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lo primero ser\u00e1 <strong>presentar un escrito al ayuntamiento<\/strong>, solicitando rectificaci\u00f3n y la devoluci\u00f3n de la plusval\u00eda. En \u00e9l debes reflejar la cantidad que reclamas en concepto de plusval\u00eda indebidamente cobrada.<\/li>\n\n\n\n<li>Si el ayuntamiento desestima tu petici\u00f3n, podr\u00e1s<strong> presentar un recurso de reposici\u00f3n<\/strong> en un plazo de un mes a partir del d\u00eda siguiente de la notificaci\u00f3n. Ten en cuenta que no podr\u00e1s promover la reclamaci\u00f3n econ\u00f3mico-administrativa hasta que el recurso se haya resuelto.<\/li>\n\n\n\n<li>En \u00faltimo lugar, si se deniega esta reclamaci\u00f3n, tendr\u00e1s que <strong>acudir por la v\u00eda judicial<\/strong>. Presentando un recurso contencioso-administrativo ante el Tribunal Superior de Justicia de la Comunidad Aut\u00f3noma correspondiente en el plazo de dos meses.<\/li>\n<\/ul>\n\n\n<p>[irp posts=\u00bb2833&#8243; name=\u00bb\u00bfC\u00f3mo calcular los gastos en la venta de un piso?\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Documentaci\u00f3n necesaria&nbsp;<\/h2>\n\n\n\n<p>Junto con todo lo anterior comentado, necesitar\u00e1s la documentaci\u00f3n pertinente para poder llevar a cabo las gestiones, son las siguientes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Escritura p\u00fablica de la compra de la vivienda<\/strong>, en el que conste el precio de la compra.<\/li>\n\n\n\n<li><strong>Escritura p\u00fablica de la venta del inmueble<\/strong>, en el que conste el precio de la venta.<\/li>\n\n\n\n<li><strong>Justificante del ingreso del impuesto<\/strong> en el ayuntamiento, en el que quede constancia de la cantidad pagada en concepto de plusval\u00eda.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Vende tu vivienda sin complicaciones <\/h2>\n\n\n\n<p>En Housfy contamos con un equipo de profesionales que te ayudaran a <strong><a href=\"https:\/\/housfy.com\/vender-pisos\">vender un piso<\/a><\/strong> hasta 3 veces m\u00e1s r\u00e1pido. Hacemos la gesti\u00f3n totalmente <strong>online, r\u00e1pido y f\u00e1cil<\/strong>. Adem\u00e1s, con nosotros ahorrar\u00e1s dinero, nada que ver con una agencia tradicional. No lo pienses m\u00e1s y \u00a1ponte en contacto con nuestros especialistas!<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-33\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_33 module_id_33  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"33\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfCu\u00e1nto vale mi casa? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfCu\u00e1nto vale mi casa?<\/h3><h4 class=\"hustle-subtitle\">Realiza la valoraci\u00f3n online y gratuita de tu vivienda en pocos minutos<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/valoracion-piso?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_valoracion_blog&#038;utm_term=valoracion_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">VALORAR VIVIENDA GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En una operaci\u00f3n de compraventa se realizan muchas acciones, desde el momento de vender un piso hasta la firma y entrega de llaves. Pero no hay que olvidar que este procedimiento tambi\u00e9n requieren hacer el pago de ciertos tributos. C\u00f3mo es el impuesto de plusval\u00eda municipal. Despu\u00e9s de los \u00faltimos y lo dictaminado por el Tribunal Constitucional, es normal que te preguntes \u00bfTengo que pagarlo? Si lo he hecho, \u00bfC\u00f3mo solicito la devoluci\u00f3n plusval\u00eda municipal? A continuaci\u00f3n, te despejamos todas las dudas que tengas al respecto. Impuesto de plusval\u00eda municipal&nbsp; Lo primero que hay que aclarar es \u00bfqu\u00e9 es el <\/p>\n","protected":false},"author":1,"featured_media":34971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-34969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2022\/05\/31095734\/como-reclamar-el-impuesto-de-plusvalia-municipal-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/34969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=34969"}],"version-history":[{"count":12,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/34969\/revisions"}],"predecessor-version":[{"id":60767,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/34969\/revisions\/60767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/34971"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=34969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=34969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=34969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}