{"id":37046,"date":"2022-06-29T14:55:10","date_gmt":"2022-06-29T14:55:10","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=37046"},"modified":"2026-05-29T08:00:50","modified_gmt":"2026-05-29T08:00:50","slug":"la-inspeccion-tecnica-de-edificios-en-cataluna-como-funciona","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/la-inspeccion-tecnica-de-edificios-en-cataluna-como-funciona\/","title":{"rendered":"La inspecci\u00f3n t\u00e9cnica de edificios en Catalu\u00f1a: \u00bfc\u00f3mo funciona?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tanto para comprar o<strong> <\/strong><a href=\"https:\/\/housfy.com\/vender-pisos\"><strong>vender un piso<\/strong><\/a>, lleva un proceso que implica una serie de <strong>documentaci\u00f3n obligatoria<\/strong> para hacer la operaci\u00f3n inmobiliaria de forma correcta y legal. Adem\u00e1s, toda ella ha de estar en vigor para que tenga efectividad. Alguna\u00a0documentaci\u00f3n est\u00e1 relacionada con la hipoteca en el momento de <a href=\"https:\/\/housfy.com\/venta-inmuebles\"><strong>comprar una casa<\/strong><\/a>, otra tienen que ver con los <strong>impuestos <\/strong>que se tienen que asumir y luego est\u00e1n los <strong>certificados <\/strong>que se deben solicitar. Comprobar que un inmueble cumple las condiciones de habitabilidad es crucial, por eso se realiza la <strong>inspecci\u00f3n t\u00e9cnica de edificios (ITE) en Catalu\u00f1a<\/strong>. Si quieres saber m\u00e1s, te lo comentamos a continuaci\u00f3n.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><div\r\n\t\t\t\tid=\"hustle-embedded-id-52\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_52 module_id_52   hustle-size--custom\"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"52\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"Vende piso en Barcelona con un experto en la zona popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">Vende piso en Barcelona con un experto en la zona<\/h3><h4 class=\"hustle-subtitle\">Te acompa\u00f1ar\u00e1 para vender hasta 3 veces m\u00e1s r\u00e1pido y pagar\u00e1s solo si vendes<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/barcelona\/barcelona?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_vender_inmueble_barcelona_blog&#038;utm_term=vender_inmueble_barcelona_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">INF\u00d3RMATE GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es la Inspecci\u00f3n T\u00e9cnica de Edificios (ITE)?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Generalitat aprob\u00f3 el Decreto 187\/2010, donde se establece la <strong><a href=\"https:\/\/housfy.com\/blog\/que-es-la-inspeccion-tecnica-de-edificios\/\">Inspecci\u00f3n T\u00e9cnica de Edificios<\/a><\/strong> (ITE) en Catalu\u00f1a, que consiste en la <strong>inspecci\u00f3n visual del edificio<\/strong> por parte de un t\u00e9cnico competente, como un arquitecto, aparejador o ingeniero. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La finalidad es <strong>determinar su estado<\/strong> para cumplir el deber de conservaci\u00f3n, mantenimiento y rehabilitaci\u00f3n de las viviendas. Todo ello como una medida imprescindible para <strong>impedir la degradaci\u00f3n<\/strong> del parque inmobiliario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El organismo responsable que se encarga de que se cumplan los requisitos son el departamento de derechos sociales y la agencia de la vivienda en Catalu\u00f1a. Y ser\u00e1 la administraci\u00f3n que, con base a este informe elaborado de inspecci\u00f3n t\u00e9cnica, emitir\u00e1 el certificado de aptitud que se requiere para la escritura de compraventa.<\/p>\n\n\n<p>[irp posts=\u00bb1599&#8243; name=\u00bb\u00bfQu\u00e9 es la c\u00e9dula de habitabilidad y qu\u00e9 tipos hay?\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fases de una inspecci\u00f3n t\u00e9cnica de edificios en Catalu\u00f1a<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la evaluaci\u00f3n del edificio se deben seguir unos <strong>pasos previos <\/strong>para proceder al estudio del estado y las condiciones:\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Encargo<\/li>\n\n\n\n<li>Proceso de informaci\u00f3n a vecinos del procedimiento<\/li>\n\n\n\n<li>Visitas de toma de datos<\/li>\n\n\n\n<li>Redacci\u00f3n del informe<\/li>\n\n\n\n<li>Presentaci\u00f3n del informe a la comunidad de vecinos <\/li>\n\n\n\n<li>Tr\u00e1mite burocr\u00e1tico<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 edificios est\u00e1n obligados a realizar la ITE?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los edificios que est\u00e1n obligados a cumplir con la Inspecci\u00f3n T\u00e9cnica de Edificios en Catalu\u00f1a son los que tiene <strong>m\u00e1s de 45 a\u00f1os<\/strong>, y estos deber\u00e1n efectuarla <strong>cada 10 a\u00f1os<\/strong>. Tambi\u00e9n es un requisito para aquellos edificios que est\u00e9n declarados en ruina o se haya llevado a cabo una <strong><a href=\"https:\/\/housfy.com\/blog\/diferencia-rehabilitacion-y-reforma\/\">rehabilitaci\u00f3n integral<\/a><\/strong> reciente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se deber\u00e1n incluir en la obligaci\u00f3n de hacer el examen t\u00e9cnico las propiedades que:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cuando lo determinen programas u ordenanzas locales, o por petici\u00f3n a trav\u00e9s de un requerimiento del ayuntamiento del municipio d\u00f3nde se localiza el inmueble o de la Agencia de la Vivienda de Catalu\u00f1a.<\/li>\n\n\n\n<li>Cuando el edificio o viviendas del edificio se deban acoger a programas p\u00fablicos de ayudas para el fomento de la rehabilitaci\u00f3n.<\/li>\n\n\n\n<li>Lleven a cabo rehabilitaciones integrales y hayan obtenido <strong><a href=\"https:\/\/housfy.com\/blog\/licencia-primera-ocupacion\/\">licencia municipal de primera ocupaci\u00f3n<\/a><\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quedan excluidos de esta lista los edificios sobre los que se haya iniciado el expediente de declaraci\u00f3n de ruina.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 calificaciones pueden resultar del estudio?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que el t\u00e9cnico tenga la <strong>valoraci\u00f3n de la vivienda<\/strong>, se pueden obtener diferentes resultados en funci\u00f3n de si <strong>cumplen o no con las condiciones<\/strong>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deficiencias muy graves<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Son las que, por su nivel de seriedad, representan un<strong> riesgo inminente <\/strong>y generalizado para la estabilidad del edificio y la seguridad de las personas y bienes, y requieren una <strong>intervenci\u00f3n inmediata<\/strong> consistente en el <strong>desalojo <\/strong>del edificio o la adopci\u00f3n de otras medidas de car\u00e1cter urgente y cautelar. O en su defecto la declaraci\u00f3n de ruina del edificio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deficiencias graves<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Representan tambi\u00e9n un <strong>riesgo inminente <\/strong>para la estabilidad de determinados elementos del edificio o <strong>grandes problemas<\/strong> de salubridad. Al igual que las primeras deficiencias, presuponen un peligro para la seguridad de las personas o bienes. Por lo que necesitan una<strong> primera fase <\/strong>de adopci\u00f3n de medidas cautelares y una <strong>segunda fase <\/strong>de ejecuci\u00f3n de las obras para subsanar estas deficiencias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deficiencias importantes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan no presentando en un principio un riesgo inminente ni para la estabilidad del edificio ni para la seguridad de las personas, <strong>afectan<\/strong> su salubridad y funcionalidad de la vivienda. Por lo que hace falta una <strong>intervenci\u00f3n correctora<\/strong> que no puede quedar relegada a trabajos de mantenimiento.\u00a0\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deficiencias leves<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Son todas aquellas valoraciones no incluidas en los apartados anteriores. Que hacen necesaria la realizaci\u00f3n de <strong>trabajos de mantenimiento preventivo<\/strong> para evitar su agravamiento, as\u00ed para que eviten nuevas apariciones de deficiencias.<\/p>\n\n\n<p>[irp posts=\u00bb1477&#8243; name=\u00bbCertificado Energ\u00e9tico: c\u00f3mo conseguir tu etiqueta\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vende tu vivienda en un clic <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya sabes todo acerca de la Inspecci\u00f3n T\u00e9cnica de Edificios en Catalu\u00f1a, podr\u00e1s <strong><a href=\"https:\/\/housfy.com\/vender-pisos\">vender un piso<\/a><\/strong> sin problemas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es m\u00e1s, desde Housfy podemos ayudarte a conseguirlo hasta tres veces m\u00e1s r\u00e1pido que en una inmobiliaria tradicional, gracias a la tecnolog\u00eda <strong>Housfy Connect\u00ae<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro equipo de expertos inmobiliarios te acompa\u00f1ar\u00e1n para que el proceso de venta sea lo m\u00e1s <strong>r\u00e1pido y c\u00f3modo <\/strong>para ti. No olvides que a trav\u00e9s de nuestra plataforma podr\u00e1s obtener una <strong><a href=\"https:\/\/housfy.com\/vender-pisos\">valoraci\u00f3n de tu piso<\/a><\/strong> de forma gratuita, online y sin compromiso. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No esperes m\u00e1s, \u00a1Adelante!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><div\r\n\t\t\t\tid=\"hustle-embedded-id-33\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_33 module_id_33  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"33\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfCu\u00e1nto vale mi casa? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfCu\u00e1nto vale mi casa?<\/h3><h4 class=\"hustle-subtitle\">Realiza la valoraci\u00f3n online y gratuita de tu vivienda en pocos minutos<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/valoracion-piso?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_valoracion_blog&#038;utm_term=valoracion_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">VALORAR VIVIENDA GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tanto para comprar o vender un piso, lleva un proceso que implica una serie de documentaci\u00f3n obligatoria para hacer la operaci\u00f3n inmobiliaria de forma correcta y legal. Adem\u00e1s, toda ella ha de estar en vigor para que tenga efectividad. Alguna\u00a0documentaci\u00f3n est\u00e1 relacionada con la hipoteca en el momento de comprar una casa, otra tienen que ver con los impuestos que se tienen que asumir y luego est\u00e1n los certificados que se deben solicitar. Comprobar que un inmueble cumple las condiciones de habitabilidad es crucial, por eso se realiza la inspecci\u00f3n t\u00e9cnica de edificios (ITE) en Catalu\u00f1a. Si quieres saber m\u00e1s, <\/p>\n","protected":false},"author":60,"featured_media":37050,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[570],"class_list":["post-37046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vender-piso","tag-cataluna","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2022\/06\/29144412\/mansour-kiaei-Ye7qY2c79iM-unsplash-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/37046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=37046"}],"version-history":[{"count":10,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/37046\/revisions"}],"predecessor-version":[{"id":59236,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/37046\/revisions\/59236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/37050"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=37046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=37046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=37046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}