{"id":3750,"date":"2018-11-06T15:44:07","date_gmt":"2018-11-06T15:44:07","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=3750"},"modified":"2023-03-15T12:29:52","modified_gmt":"2023-03-15T12:29:52","slug":"bombillas-led-deberias-poner-casa","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/bombillas-led-deberias-poner-casa\/","title":{"rendered":"\u00bfQu\u00e9 bombillas LED deber\u00edas poner en casa?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Si quieres <a href=\"https:\/\/housfy.com\/blog\/factura-de-la-luz-claves\/\">economizar tu factura de la luz<\/a> y sabes que la <a href=\"https:\/\/housfy.com\/blog\/guia-dar-alta-la-luz-vivienda\/\">iluminaci\u00f3n de tu hogar<\/a> no es un asunto cualquiera, desde Housfy queremos proponerte una soluci\u00f3n. En el siguiente art\u00edculo te mostraremos herramientas \u00fatiles para adquirir unas buenas bombillas LED. <\/span><\/p>\n<p>Obtener una buena bombilla no solo trae <a href=\"https:\/\/housfy.com\/blog\/trucos-para-ahorrar-dinero-en-casa\/\">beneficios econ\u00f3micos<\/a>, tambi\u00e9n minimiza el cansancio de la vista, facilita la lectura y crea una mejor sensaci\u00f3n en el ambiente. Observamos que con las bombillas LED tenemos m\u00e1s opciones a la hora de elegir. Consumen menos, son menos contaminantes y con vida \u00fatil m\u00e1s larga, pero tambi\u00e9n son mucho m\u00e1s caras que las de bajo consumo.<\/p>\n<p>Es normal que al ver su precio nos entren dudas, ya que hay modelos con gran diferencia y algunas caracter\u00edsticas que debemos tener en cuenta para acertar en la que cubra mejor con nuestras necesidades.<\/p>\n<p>Para empezar, es aconsejable evaluar la oferta del producto. Podemos encontrar muchas opciones que incluyan m\u00e1s de una unidad, ayud\u00e1ndonos a ahorrar dinero y a mantener una uniformidad en la iluminaci\u00f3n.<\/p>\n<h2>\u00bfC\u00f3mo escoger unas bombillas LED?<\/h2>\n<p>Antes de decidirnos a comprar una bombilla LED debemos tener en cuenta distintos factores que encontraremos en la etiqueta energ\u00e9tica de la bombilla.<\/p>\n<h3><b>Apariencia<\/b><\/h3>\n<ul>\n<li>El tono de luz que obtenemos con determinada temperatura de color.<\/li>\n<li>El \u00edndice de rendimiento o reproducci\u00f3n crom\u00e1tica. Se indica en una escala entre el 0 y el 100. Cuanto m\u00e1s alta, m\u00e1s calidad de luz nos proporcionar\u00e1 la bombilla. Una de las ventajas de las bombillas LED es que est\u00e1n muy relacionadas con la calidad de la luz, representan la fiabilidad de la luz natural.<\/li>\n<li>La temperatura del color, medida en grados Kelvin. Nos indica el tono de luz de la fuente, cuanto m\u00e1s elevada sea, m\u00e1s fr\u00eda y azul se ver\u00e1 la fuente de luz blanca.<\/li>\n<li>El \u00e1ngulo de luz, lo determinaremos seg\u00fan el tipo de iluminaci\u00f3n que busquemos: m\u00e1s amplia o m\u00e1s concentrada.<\/li>\n<\/ul>\n<h3><b>Funcionamiento y duraci\u00f3n<\/b><\/h3>\n<ul>\n<li>Los ciclos de encendido, nos indica las veces que podemos encender y apagar la bombilla antes de que empiece a fallar. En el caso de las bombillas LED es instant\u00e1neo. Es el tiempo de encendido o de precalentamiento hasta que la bombilla alcanza el 60% de luminosidad.<\/li>\n<li>La regulaci\u00f3n, si la queremos regulable debemos asegurarnos de que es compatible, se ve indicado por el fabricante.<\/li>\n<li>El factor de mantenimiento del flujo luminoso, es el porcentaje de flujo luminoso que el fabricante indica cuando hayan finalizado las horas de vida \u00fatil establecidas en las condiciones. La cifra adecuada suele ser 0.7.<\/li>\n<\/ul>\n<p>Cabe destacar que las bombillas LED padecen mucho el calor y los excesos de tensi\u00f3n, es decir, tener muchos electrodom\u00e9sticos en uso a la vez. Si en casa tienes una corriente inestable puede hacer que la bombilla dure mucho menos.<\/p>\n<h3><b>Eficiencia y consumo<\/b><\/h3>\n<ul>\n<li>Equivalencia en vatios, es decir, la potencia equivalente de una l\u00e1mpara incandescente con la misma producci\u00f3n de luz.<\/li>\n<li>La potencia, lo que consume la bombilla, se mide en vatios. Cuanta menor potencia, menor consumo.<\/li>\n<li>La clase de eficiencia energ\u00e9tica, igual que en los electrodom\u00e9sticos. Es una forma visual de conocer c\u00f3mo de eficaz es la bombilla. La eficiencia L\u00famen es una de las claves de las bombillas LED, se sit\u00faa entre 40Lm\/w y los 90Lm\/w. Deber\u00edamos exigir al menos 60Lm\/w*.<\/li>\n<\/ul>\n<p><span style=\"font-weight: 10;\">* L<\/span><span style=\"font-weight: 10;\">m\/W significa rendimiento luminoso, es decir la relaci\u00f3n entre el flujo luminoso emitido y la potencia consumida por la fuente.<\/span><\/p>\n<h3><b>\u00bfQu\u00e9 marca de bombillas LED deber\u00eda comprar?<\/b><\/h3>\n<p>Una vez dispuestos a comprar una bombilla LED, es importante considerar las cuestiones descritas anteriormente \u00a0en la <a href=\"https:\/\/housfy.com\/blog\/que-debe-contener-una-etiqueta-energetica\/\">etiqueta energ\u00e9tica<\/a>. En el mercado existen muchas alternativas de marcas populares y recomendadas que nos pueden hacer dudar un poco a la hora de escoger la adecuada. Desde Housfy nos hemos tomado la libertad de recomendarte una \u00e1mplia oferta de marcas para que escojas las que m\u00e1s se adapten a tu vivienda. Las m\u00e1s populares son Philips, Osram, AmazonBasics, Ikea, LG, Liqpp, Taotronics, Aigostar, GE, etc.<\/p>\n<p>En Housfy te proporcionamos todo el asesoramiento que necesites para vender tu piso, desde el principio hasta el fin del proceso. Gracias a nuestros expertos dejar\u00e1s de preocuparte de c\u00f3mo vender tu piso y comenzar\u00e1s a pensar en que invertir el dinero ahorrado en la compraventa de tu inmueble. \u00a1<a href=\"https:\/\/housfy.com\/vender-pisos\/expertos-inmobiliarios\"><strong>Contacta con nuestros expertos<\/strong><\/a>\u00a0e inf\u00f3rmate sin compromiso!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si quieres economizar tu factura de la luz y sabes que la iluminaci\u00f3n de tu hogar no es un asunto cualquiera, desde Housfy queremos proponerte una soluci\u00f3n. En el siguiente art\u00edculo te mostraremos herramientas \u00fatiles para adquirir unas buenas bombillas LED. Obtener una buena bombilla no solo trae beneficios econ\u00f3micos, tambi\u00e9n minimiza el cansancio de la vista, facilita la lectura y crea una mejor sensaci\u00f3n en el ambiente. Observamos que con las bombillas LED tenemos m\u00e1s opciones a la hora de elegir. Consumen menos, son menos contaminantes y con vida \u00fatil m\u00e1s larga, pero tambi\u00e9n son mucho m\u00e1s caras que <\/p>\n","protected":false},"author":1,"featured_media":3753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122],"tags":[],"class_list":["post-3750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-decoracion","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2018\/11\/07152600\/vera-cho-785625-unsplash.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/3750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=3750"}],"version-history":[{"count":7,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/3750\/revisions"}],"predecessor-version":[{"id":46155,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/3750\/revisions\/46155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/3753"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=3750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=3750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=3750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}