{"id":39944,"date":"2022-08-25T08:00:00","date_gmt":"2022-08-25T08:00:00","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=39944"},"modified":"2026-05-29T07:59:16","modified_gmt":"2026-05-29T07:59:16","slug":"que-documentos-debe-entregar-el-vendedor-de-una-vivienda","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/que-documentos-debe-entregar-el-vendedor-de-una-vivienda\/","title":{"rendered":"\u00bfQu\u00e9 debes entregar para la compraventa de tu vivienda?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Puede haber una larga lista de motivos para <a href=\"https:\/\/housfy.com\/vender-pisos\"><strong>vender una vivienda<\/strong><\/a>: mudarse a una nueva casa, vender una casa heredada o deshacerse de esa vivienda que estaba en alquiler. Pero <strong>\u00bfqu\u00e9 documentos debe entregar el vendedor en la compraventa vivienda?<\/strong> En este art\u00edculo te explicamos la informaci\u00f3n necesaria para que consigas resolver esas dudas que puedas tener al respecto.<\/p>\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-33\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_33 module_id_33  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"33\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfCu\u00e1nto vale mi casa? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfCu\u00e1nto vale mi casa?<\/h3><h4 class=\"hustle-subtitle\">Realiza la valoraci\u00f3n online y gratuita de tu vivienda en pocos minutos<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/valoracion-piso?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_valoracion_blog&#038;utm_term=valoracion_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">VALORAR VIVIENDA GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Obtener toda la documentaci\u00f3n disponible y actualizada<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez tomada la decisi\u00f3n de <strong><a href=\"https:\/\/housfy.com\/blog\/cuanto-cobra-una-inmobiliaria-venta-piso\/\">vender un inmueble<\/a><\/strong>, pones todo en marcha para entregar finalmente las llaves al nuevo propietario. Pero, antes de ese \u00faltimo paso, se deben reunir todos los documentos para posteriormente <strong>ir al notario y finiquitar la venta <\/strong>de la casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te recomendamos que lleves un <strong>control exhaustivo de toda la documentaci\u00f3n<\/strong> que debes de reunir y entregar. La falta de alg\u00fan papel puede impedir la compraventa e, incluso, puede hacer perder a un comprador. Tambi\u00e9n aconsejamos que hagas una <strong><a href=\"https:\/\/housfy.com\/cuanto-vale-mi-casa\">valoraci\u00f3n de viviendas gratis<\/a><\/strong> antes de ponerte en marcha con todos los tr\u00e1mites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[irp posts=\u00bb2300&#8243; name=\u00bb3 simples pasos para vender r\u00e1pido mi casa\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 documentos debe entregar el vendedor en la compraventa de su vivienda?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Te aconsejamos que mires con mucho ojo el <strong>listado de los 11 documentos<\/strong>, as\u00ed no te faltar\u00e1 nada y todo ir\u00e1 seg\u00fan lo previsto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. DNI o tarjeta de residencia<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario presentar el <strong>documento de identidad de cada una de las partes<\/strong> y comprobar su vigencia. En caso de presentar tu pasaporte, tendr\u00e1s que acreditar el N\u00famero de Identificaci\u00f3n Fiscal (NIF). Si no recuerdas el nombre del notario con el que firmaste, en el documento de nota simple, que detallamos a continuaci\u00f3n, encontrar\u00e1s la informaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2.<\/strong> <strong>Nota simple del registro de la propiedad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este documento se\u00f1ala qui\u00e9n es el<strong> propietario de la vivienda y las caracter\u00edsticas<\/strong> de esta misma. Tambi\u00e9n indica si el <strong><a href=\"https:\/\/housfy.com\/blog\/saber-una-vivienda-esta-embargada\/\">inmueble tiene cargas<\/a><\/strong> o deudas pendientes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Recibo del \u00faltimo pago del impuesto sobre bienes inmuebles (IBI)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El IBI <strong>es un tributo que pagan todos los propietarios<\/strong> por ser due\u00f1os de una vivienda. Con este certificado demuestras que est\u00e1s al d\u00eda con el pago del impuesto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4.<\/strong> <strong>Certificado energ\u00e9tico<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un <strong><a href=\"https:\/\/housfy.com\/vender-pisos\/guias\/post\/certificado-energetico\">documento que informa sobre el consumo energ\u00e9tico<\/a> <\/strong>de tu inmueble en condiciones normales. El documento lo otorga un t\u00e9cnico acreditado y es el que refleja las caracter\u00edsticas energ\u00e9ticas de la vivienda como el consumo o las emisiones de CO2.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5.<\/strong> <strong>C\u00e9dula de habitabilidad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el <strong>documento que acredita que una vivienda cumple los requisitos de habitabilidad<\/strong> fijados por la ley. Es decir, que<strong> es apta para ser habitada<\/strong>. Es obligatorio en algunas comunidades como Catalunya, Canarias, Cantabria, Comunitat Valenciana, Navarra, Murcia, Baleares, Extremadura y La Rioja.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para tramitarlo por primera vez, o renovarlo, es necesario como en el caso del certificado energ\u00e9tico, un t\u00e9cnico cualificado. Sin embargo, si existe una c\u00e9dula vigente solo tendr\u00e1s que preocuparte de <strong>solicitar una copia al Ayuntamiento<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6.<\/strong> <strong>Escritura de propiedad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Esta escritura es un documento p\u00fablico otorgado ante notario que ofrece la m\u00e1xima seguridad jur\u00eddica conforme <strong>un inmueble es de nuestra propiedad<\/strong>. Si no tienes a disposici\u00f3n la <strong><a href=\"https:\/\/housfy.com\/blog\/registrar-una-casa-sin-escritura\/\">escritura de propiedad<\/a><\/strong>, podr\u00e1s pedir una copia al notario.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>7.<\/strong> <strong>Certificado de Inspecci\u00f3n T\u00e9cnica del Edificio (ITE)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este documento certifica que un edificio con cierta antig\u00fcedad ha pasado una inspecci\u00f3n y que <strong>cumple con todos los requisitos de seguridad<\/strong>, es obligatorio para edificios de m\u00e1s de <strong>50 a\u00f1os<\/strong>, aunque puede variar seg\u00fan la localidad. Como los anteriores certificados, tambi\u00e9n lo realiza un t\u00e9cnico homologado. Entre algunas de sus revisiones, est\u00e1n las fachadas, tuber\u00edas o azoteas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>8.<\/strong> <strong>Certificado de estar al corriente de gastos de la comunidad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este documento se puede pedir al Presidente de la comunidad o al administrador. El certificado indica que ese mismo a\u00f1o <strong>el due\u00f1o no tiene ninguna deuda con la comunidad<\/strong> de vecinos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>9.<\/strong> <strong>Contrato de arras<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un acuerdo donde el comprador de la vivienda efect\u00faa el pago de una cantidad, normalmente el 10 % del precio del inmueble pactado, al vendedor para<strong> la reserva de la venta<\/strong>. Si se firma este contrato con el comprador, el notario utilizar\u00e1 este documento como base para elaborar la escritura de compraventa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, te dejamos nuestra <strong><a href=\"https:\/\/housfy.com\/vender-pisos\/guias\/post\/contrato-de-arras\">gu\u00eda del contrato de arras<\/a><\/strong> donde tendr\u00e1s toda la informaci\u00f3n a mano que necesites saber sobre este documento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>10.<\/strong> <strong>Certificado de deuda pendiente<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este documento se debe presentar <strong>en el caso de que tengas que cancelar la hipoteca<\/strong> con el dinero de la venta. Este certificado te lo puede facilitar el mismo banco de forma gratuita. As\u00ed, en el momento de la firma, el comprador extender\u00e1 un cheque a nombre del banco del vendedor y la deuda quedar\u00e1 saldada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>11. \u00daltimos recibos de suministro pagados<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es conveniente certificar que <strong>el propietario est\u00e1 al corriente<\/strong> con el pago de la luz, el agua, el tel\u00e9fono o el gas de la vivienda. Las facturas de los servicios pagados aportan credibilidad como vendedor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[irp posts=\u00bb2033&#8243; name=\u00bb\u00bfCu\u00e1nto cuesta vender un piso en Espa\u00f1a?\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Obt\u00e9n la ayuda que necesitas para la compraventa de tu vivienda<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEst\u00e1s pensando en vender un inmueble? Saber exactamente qu\u00e9 documentos debe entregar el vendedor de una vivienda puede ser a veces un poco confuso. Por eso, en <strong><a href=\"https:\/\/housfy.com\/vender-pisos\">Housfy<\/a><\/strong> te ayudamos en todo el proceso para vender tu propiedad, un equipo de profesionales estar\u00e1 a tu disposici\u00f3n y se encargar\u00e1 de todas las gestiones.<\/p>\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-33\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_33 module_id_33  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"33\"\r\n\t\t\tdata-render-id=\"1\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfCu\u00e1nto vale mi casa? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfCu\u00e1nto vale mi casa?<\/h3><h4 class=\"hustle-subtitle\">Realiza la valoraci\u00f3n online y gratuita de tu vivienda en pocos minutos<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/valoracion-piso?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_valoracion_blog&#038;utm_term=valoracion_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">VALORAR VIVIENDA GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Puede haber una larga lista de motivos para vender una vivienda: mudarse a una nueva casa, vender una casa heredada o deshacerse de esa vivienda que estaba en alquiler. Pero \u00bfqu\u00e9 documentos debe entregar el vendedor en la compraventa vivienda? En este art\u00edculo te explicamos la informaci\u00f3n necesaria para que consigas resolver esas dudas que puedas tener al respecto. Obtener toda la documentaci\u00f3n disponible y actualizada Una vez tomada la decisi\u00f3n de vender un inmueble, pones todo en marcha para entregar finalmente las llaves al nuevo propietario. Pero, antes de ese \u00faltimo paso, se deben reunir todos los documentos para <\/p>\n","protected":false},"author":60,"featured_media":60002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-39944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2022\/08\/12145519\/que-documentos-debe-entregar-el-vendedor-de-una-vivienda-1-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/39944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=39944"}],"version-history":[{"count":28,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/39944\/revisions"}],"predecessor-version":[{"id":60059,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/39944\/revisions\/60059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/60002"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=39944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=39944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=39944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}