{"id":4751,"date":"2019-01-18T17:41:27","date_gmt":"2019-01-18T16:41:27","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=4751"},"modified":"2026-06-16T16:09:43","modified_gmt":"2026-06-16T16:09:43","slug":"comprar-un-piso-de-segunda-mano","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/comprar-un-piso-de-segunda-mano\/","title":{"rendered":"\u00bfC\u00f3mo comprar un piso de segunda mano?"},"content":{"rendered":"<p>Ya lo has decidido: quieres <a href=\"https:\/\/housfy.com\/venta-pisos\">comprar un piso de segunda mano<\/a>. Debes saber que no es lo mismo comprar un inmueble de obra nueva que uno que haya sido habilitado. Seg\u00fan datos del Instituto Nacional de Estad\u00edstica m\u00e1s del 80% de las compras de inmuebles realizadas el pasado 2018 fueron de viviendas usadas.<\/p>\n<p>Comprar un inmueble de segunda mano tiene muchas ventajas tales como el precio, la presi\u00f3n fiscal, la localizaci\u00f3n y el acceso inmediato a vivir en la propiedad al comprarla. No obstante, antes de adquirirla tienes que tener en cuenta algunos factores importantes para no llevarte sorpresas desagradables.<\/p>\n<p>[irp posts=\u00bb4683&#8243; name=\u00bbAyudas para el alquiler o compra de una vivienda\u00bb]<\/p>\n<h2>Consejos para comprar un piso de segunda mano<\/h2>\n<h3><strong>Con el paso de los a\u00f1os vienen los da\u00f1os<\/strong><\/h3>\n<p>El inconveniente primordial de comprar un piso de segunda mano son los a\u00f1os de construcci\u00f3n. El tiempo desgasta y estropea al inmueble y antes de comprar deber\u00e1s fijarte siempre en distintas cuestiones:<\/p>\n<ul>\n<li>F\u00edjate bien en los acabados y las calidades de la construcci\u00f3n porque su buen estado te garantizar\u00e1 seguridad y perdurabilidad. Observa si la pintura est\u00e1 agrietada o abombada, si las baldosas est\u00e1n levantadas o rotas si el suelo necesita renovarse, los z\u00f3calos, molduras&#8230;<\/li>\n<li>Las puertas y ventanas deben estar bien aisladas y por supuesto abrir y cerrar bien y herm\u00e9ticamente, as\u00ed como proporcionar luz y ventilaci\u00f3n. Cambiarlas es un gasto a tener en cuenta.<\/li>\n<li>Los grifos de los ba\u00f1os y la cocina puede tener p\u00e9rdidas, estar oxidados o tener poca presi\u00f3n. Comprueba que puedan abrirse sin inconvenientes en el flujo del agua.<\/li>\n<li>No dejes de mirar si hay humedades en las paredes.<\/li>\n<li>Si olfateas malos olores puede ser que las tuber\u00edas de la cocina o los ba\u00f1os est\u00e9n en mal estado, debes tenerlo en cuenta.<\/li>\n<li>La instalaci\u00f3n el\u00e9ctrica tambi\u00e9n es un punto a considerar. Observa que hayan suficientes enchufes, en buen estado y bien distribuidos por todo el inmueble.<\/li>\n<\/ul>\n<div id=\"attachment_27798\" style=\"width: 1090px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-27798\"  class=\"wp-image-27798 size-full\" title=\"comprar un piso de segunda mano\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2019\/01\/24155825\/Cmo-comprar-un-piso-de-segunda-mano-Max-Quality.jpg\" alt=\"comprar un piso de segunda mano\" width=\"1080\" height=\"1920\" \/><p id=\"caption-attachment-27798\" class=\"wp-caption-text\">Infograf\u00eda sobre comprar un piso de segunda mano de housfy.<\/p><\/div>\n<h3><strong>La eficiencia energ\u00e9tica es importante<\/strong><\/h3>\n<p>Debes saber de que materiales est\u00e1n echas las fuentes <a href=\"https:\/\/housfy.com\/blog\/exencion-del-certificado-de-eficiencia-energetica\/\">energ\u00e9ticas <\/a>del inmueble. Los nuevos materiales permiten un ahorro de energ\u00eda importante y <a href=\"https:\/\/housfy.com\/blog\/5-trucos-para-ahorrar-energia-en-casa\/\">economizan <\/a>facturas mientras que los viejos las incrementan. Tambi\u00e9n tendr\u00e1s que comprobar que las ventanas y puertas permitan buen aislamiento.<\/p>\n<p>[irp posts=\u00bb3225&#8243; name=\u00bb\u00bfQu\u00e9 debe contener una etiqueta energ\u00e9tica?\u00bb]<\/p>\n<h3><strong>Analiza la finca<\/strong><\/h3>\n<p>Observa las zonas comunes y los materiales de construcci\u00f3n del edificio. Es importante detectar grietas, deficiencias o humedades. Puede que el inmueble se sit\u00fae en un bloque antiguo y debe pasar la Inspecci\u00f3n T\u00e9cnica de Edificios para cumplir las condiciones m\u00ednimas de seguridad. Si la ha pasado recientemente es una muy buena noticia, si no deber\u00e1s prepararte para afrontar gastos extras.<\/p>\n<p><img decoding=\"async\"  class=\"aligncenter wp-image-25304\" title=\"comprar piso segunda mano\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2019\/01\/28094518\/dawid-zawila-psOm5G96wyk-unsplash-100x67.jpg\" alt=\"comprar piso segunda mano\" width=\"700\" height=\"467\" \/><\/p>\n<h5><\/h5>\n<h3><strong>Conoce el barrio<\/strong><\/h3>\n<p>Resultar\u00e1 beneficioso al comprar un piso de segunda mano conocer la situaci\u00f3n de la vivienda en t\u00e9rminos urban\u00edsticos consultando al Ayuntamiento de la localidad si tiene planes de construcci\u00f3n cerca de la vivienda.<\/p>\n<h3><strong>Recomendaciones<\/strong><\/h3>\n<p>El propietario del inmueble puede proporcionarte mucha informaci\u00f3n a la hora de comprar un piso de segunda mano. Por ejemplo el precio de la luz, comunidad, ventajas del piso, ambiente vecinal, si el piso se encuentra en<strong> <a href=\"https:\/\/housfy.com\/alquileres\">alquiler<\/a><\/strong>, etc. Tambi\u00e9n puedes pedirle el Registro de la Propiedad, en el cual podr\u00e1s comprobar qui\u00e9n es el titular y si el piso esta libre de cargas o no adem\u00e1s de los metros cuadrados reales de \u00e9ste.<\/p>\n<p>[irp posts=\u00bb3664&#8243; name=\u00bbTodo lo que tienes que saber sobre el alquiler con opci\u00f3n a compra\u00bb]<\/p>\n<p>La decisi\u00f3n de comprar un piso de segunda mano es muy importante as\u00ed que deber\u00e1s meditarla con tiempo. Haz las <a href=\"https:\/\/housfy.com\/blog\/organizar-una-casa-para-una-visita\/\">visitas <\/a>al inmueble que necesites para observar al detalle cada factor del piso. Si una vez adquirido el inmueble observas desperfectos graves de los cuales no te hab\u00edas percatado, tienes 6 meses desde la adquisici\u00f3n para reclamarlos al vendedor. Si la vivienda no tiene m\u00e1s de 10 a\u00f1os de antig\u00fcedad es posible emprender acciones legales contra el promotor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya lo has decidido: quieres comprar un piso de segunda mano. Debes saber que no es lo mismo comprar un inmueble de obra nueva que uno que haya sido habilitado. Seg\u00fan datos del Instituto Nacional de Estad\u00edstica m\u00e1s del 80% de las compras de inmuebles realizadas el pasado 2018 fueron de viviendas usadas. Comprar un inmueble de segunda mano tiene muchas ventajas tales como el precio, la presi\u00f3n fiscal, la localizaci\u00f3n y el acceso inmediato a vivir en la propiedad al comprarla. No obstante, antes de adquirirla tienes que tener en cuenta algunos factores importantes para no llevarte sorpresas desagradables. <\/p>\n","protected":false},"author":1,"featured_media":24413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-4751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2019\/01\/10103256\/lucas-franco-58884-unsplash-768x512-1.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/4751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=4751"}],"version-history":[{"count":17,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/4751\/revisions"}],"predecessor-version":[{"id":53816,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/4751\/revisions\/53816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/24413"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=4751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=4751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=4751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}