{"id":54859,"date":"2024-03-15T07:00:00","date_gmt":"2024-03-15T07:00:00","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=54859"},"modified":"2024-03-20T14:35:49","modified_gmt":"2024-03-20T14:35:49","slug":"incumplimiento-del-contrato-de-arras-acciones-y-consecuencias","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/incumplimiento-del-contrato-de-arras-acciones-y-consecuencias\/","title":{"rendered":"Incumplimiento del contrato de arras: acciones y consecuencias"},"content":{"rendered":"\n<p>Como todo acuerdo que suponga una<strong> garant\u00eda y comprometa a los implicados<\/strong>, el contrato de arras<strong> comporta consecuencias si se incumple<\/strong>, pues s\u00ed o s\u00ed<strong> <\/strong>alguien sale perjudicado, y, por tanto, tiene <strong>derecho a una compensaci\u00f3n<\/strong>. \u00bfCu\u00e1l?, \u00bfQu\u00e9 pasa con el infractor?, \u00bfC\u00f3mo se reclama?<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-40\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_40 module_id_40   hustle-size--custom\"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"40\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"Vender un piso es dif\u00edcil, hasta que no lo es popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">Vender un piso es dif\u00edcil, hasta que no lo es<\/h3><h4 class=\"hustle-subtitle\">Encontramos a tu comprador ideal 3 veces m\u00e1s r\u00e1pido<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_vender_publicitario_blog&#038;utm_term=vender_publicitario_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">\u00a1ESTOY LISTO!<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es el contrato de arras? <\/strong><\/h2>\n\n\n\n<p>En el momento de <a href=\"https:\/\/housfy.com\/vender-pisos\"><strong>vender un piso<\/strong><\/a>, se suele establecer un <strong>acuerdo escrito<\/strong> entre el comprador y el vendedor: el <strong>contrato de arras<\/strong>. Esta garant\u00eda sirve para especificar todas las <strong>condiciones <\/strong>de reserva de la vivienda y el <strong>compromiso <\/strong>con la compra.<\/p>\n\n\n\n<p>Junto con el contrato se entrega al vendedor una <strong>suma de dinero a modo de se\u00f1al<\/strong> para la reserva del inmueble. Este importe tiene un valor de <strong>entre el 5% y el 10%<\/strong> del precio de venta final, aunque huelga decir que <strong>no es un porcentaje fijo<\/strong>, as\u00ed que depender\u00e1 de cada caso, y adem\u00e1s <strong>se puede negociar<\/strong> entre comprador y vendedor.<\/p>\n\n\n\n<p>Existen varios <strong>tipos de contratos de arras <\/strong>seg\u00fan la penalizaci\u00f3n que se establezca por su incumplimiento:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arras penitenciales.<\/li>\n\n\n\n<li>Arras confirmatorias.&nbsp;<\/li>\n\n\n\n<li>Arras penales.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Se ha incumplido mi contrato de arras\u2026 \u00bfQu\u00e9 hago? <\/strong><\/h2>\n\n\n\n<p>El <a href=\"https:\/\/housfy.com\/vender-pisos\/guias\/post\/contrato-de-arras\"><strong>contrato de arras<\/strong><\/a>, a pesar de <strong>no ser obligatorio<\/strong>, es muy recomendable, ya que es la \u00fanica v\u00eda que tienen los implicados de obtener cierta <strong>seguridad en la compraventa<\/strong>. Aun as\u00ed, firmar un contrato de arras <strong>no asegura al 100% su cumplimiento<\/strong>, lo que implica que alguna de ambas partes podr\u00eda infringir alguna de las condiciones establecidas.<\/p>\n\n\n\n<p>\u00bfTe ha pasado? No te preocupes, anota las <strong>acciones<\/strong> que puedes llevar a cabo para solucionarlo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Notificar por escrito al comprador<\/strong>. Inf\u00f3rmale del incumplimiento del contrato y c\u00edtale para firmar la escritura de compraventa.<\/li>\n\n\n\n<li><strong>Solicitar ayuda a la notar\u00eda<\/strong>.<strong> <\/strong>Esta obligar\u00e1 al comprador a presentarse mediante una nueva citaci\u00f3n, si este no colabora en la primera notificaci\u00f3n amistosa.<\/li>\n\n\n\n<li><strong>Reclamar ante el juzgado<\/strong>. Si el comprador sigue sin solucionar el incumplimiento, el juzgado exigir\u00e1 la venta del inmueble o retendr\u00e1 el importe de la se\u00f1al.<\/li>\n\n\n\n<li><strong>Publicar de nuevo la vivienda en venta<\/strong>. Inicia la b\u00fasqueda de otro comprador.<\/li>\n<\/ol>\n\n\n\n<p class=\"has-background\" style=\"background-color:#ebf8ff\"><strong>Tip Housfy.<\/strong>\ud83d\udca1 Si el <strong>incumplimiento del contrato de arras es por fuerza mayor<\/strong>, el comprador podr\u00e1 presentar documentaci\u00f3n y evidencias que demuestren esta condici\u00f3n y<strong> justifiquen legalmente <\/strong>su imposibilidad de cumplir con \u00e9l.<\/p>\n\n\n\n<p>[irp posts=\u00bb54033&#8243; name=\u00bb\u00bfCu\u00e1l es la diferencia entre el contrato de arras y el de compraventa?\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Consecuencias legales de incumplir un contrato de arras<\/strong><\/h2>\n\n\n\n<p>Lo m\u00e1s recomendable es empezar por un <strong>intento de resoluci\u00f3n amistosa<\/strong> con el comprador,&nbsp; como con una renegociaci\u00f3n de los t\u00e9rminos del contrato, el desplazamiento de las fechas de cumplimiento o la cancelaci\u00f3n del acuerdo.<\/p>\n\n\n\n<p>Si esta v\u00eda no es posible, puedes optar por la <strong>judicial<\/strong>. Las <strong>consecuencias legales<\/strong> de incumplir con el contrato de arras son:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La <strong>p\u00e9rdida del dep\u00f3sito<\/strong>.<\/li>\n\n\n\n<li>La <strong>obligaci\u00f3n de indemnizaci\u00f3n<\/strong> econ\u00f3mica (que cubran las ganancias p\u00e9rdidas o costos adicionales incurridos).<\/li>\n\n\n\n<li>La <strong>anulaci\u00f3n del contrato<\/strong>.<\/li>\n\n\n\n<li>El <strong>cumplimiento forzado<\/strong> por el tribunal del contrato.<\/li>\n<\/ol>\n\n\n\n<p>Hay que decir que existen algunas diferenciaciones en las consecuencias de impago para el vendedor y el comprador:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">TIPOS DE ARRAS<\/th><th class=\"has-text-align-left\" data-align=\"left\"><strong>COMPRADOR<\/strong><\/th><th><strong>VENDEDOR<\/strong><\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Arras penitenciales<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Pierde las arras pagadas<\/td><td>Debe devolver el doble de las arras recibidas<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Arras penales<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Debe pagar una penalizaci\u00f3n adicional, que normalmente equivale al importe de las arras<\/td><td>Debe pagar una penalizaci\u00f3n, que acostumbra a ser el doble de las arras, pero puede ser otra cantidad seg\u00fan el contrato<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Arras confirmatorias<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\">Puede enfrentarse a demandas por da\u00f1os y perjuicios o ser obligado a cumplir con el contrato<\/td><td>Puede enfrentarse a demandas por da\u00f1os y perjuicios o ser obligado a cumplir con el contrato<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Tabla 1. Las consecuencias legales por el incumplimiento del contrato de arras seg\u00fan tipos<\/figcaption><\/figure>\n\n\n\n<p>Debes tener en cuenta que recurrir a un procedimiento judicial <strong>conlleva costes<\/strong>, como<strong> honorarios y de litigio<\/strong>, y a veces estos pueden llegar a <strong>superar el valor del propio contrato de arras<\/strong>.<\/p>\n\n\n\n<p>[irp posts=\u00bb54117&#8243; name=\u00bbAs\u00ed podr\u00edan afectarte las actualizaciones del valor catastral\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Modelo de Contrato de Arras Penitenciales<\/h2>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2024\/03\/20125553\/Modelo_Contrato_Arras_Penitenciales.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Modelo_Contrato_Arras_Penitenciales.\"><\/object><a id=\"wp-block-file--media-fb2564ac-8ed7-4b23-b14d-e320c6d36760\" href=\"https:\/\/housfy.com\/blog\/incumplimiento-del-contrato-de-arras-acciones-y-consecuencias\/modelo_contrato_arras_penitenciales\/\">Modelo_Contrato_Arras_Penitenciales<\/a><a href=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2024\/03\/20125553\/Modelo_Contrato_Arras_Penitenciales.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-fb2564ac-8ed7-4b23-b14d-e320c6d36760\">Descarga<\/a><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-085c5519d8034b4d893bca951f9936a3\">Este modelo corresponde a un borrador, con el que bajo ninguna circunstancia Housfy se har\u00e1 responsable de ninguna actuaci\u00f3n. Est\u00e1 sujeto a la aplicaci\u00f3n del C\u00f3digo Civil estatal, no auton\u00f3mico, y no condicionado a la obtenci\u00f3n de una hipoteca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQuieres vender tu piso? Nosotros te ayudamos <\/strong><\/h2>\n\n\n\n<p>Si vas a vender tu piso y quieres un contrato de arras, en Housfy podemos ayudarte. Nuestros <strong>expertos inmobiliarios<\/strong> te acompa\u00f1ar\u00e1n en todo el proceso de <a href=\"https:\/\/housfy.com\/venta-pisos\"><strong>venta de tu vivienda<\/strong><\/a> para que no tengas que preocuparte por nada, ni siquiera por el contrato de arras. No dudes en consultarnos si tienes alguna duda, \u00a1Estaremos encantados de atenderte!<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-32\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_32 module_id_32  \"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"32\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"Vende tu casa consiguiendo m\u00e1s por menos popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">Vende tu casa consiguiendo m\u00e1s por menos<\/h3><h4 class=\"hustle-subtitle\">Pagar mucho por recibir poco es del pasado<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_vender_inmueble_blog&#038;utm_term=vender_inmueble_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">INF\u00d3RMATE GRATIS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como todo acuerdo que suponga una garant\u00eda y comprometa a los implicados, el contrato de arras comporta consecuencias si se incumple, pues s\u00ed o s\u00ed alguien sale perjudicado, y, por tanto, tiene derecho a una compensaci\u00f3n. \u00bfCu\u00e1l?, \u00bfQu\u00e9 pasa con el infractor?, \u00bfC\u00f3mo se reclama? \u00bfQu\u00e9 es el contrato de arras? En el momento de vender un piso, se suele establecer un acuerdo escrito entre el comprador y el vendedor: el contrato de arras. Esta garant\u00eda sirve para especificar todas las condiciones de reserva de la vivienda y el compromiso con la compra. Junto con el contrato se entrega al <\/p>\n","protected":false},"author":52,"featured_media":54865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-54859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2024\/03\/08115935\/contrato-de-arras-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/54859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=54859"}],"version-history":[{"count":12,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/54859\/revisions"}],"predecessor-version":[{"id":55101,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/54859\/revisions\/55101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/54865"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=54859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=54859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=54859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}