{"id":55345,"date":"2024-04-05T06:58:00","date_gmt":"2024-04-05T06:58:00","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=55345"},"modified":"2025-03-07T13:14:21","modified_gmt":"2025-03-07T13:14:21","slug":"que-impuestos-hay-que-pagar-por-vender-un-piso-diferencias-entre-la-plusvalia-y-el-irpf","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/que-impuestos-hay-que-pagar-por-vender-un-piso-diferencias-entre-la-plusvalia-y-el-irpf\/","title":{"rendered":"\u00bfQu\u00e9 impuestos hay que pagar por vender un piso? Diferencias entre la plusval\u00eda y el IRPF"},"content":{"rendered":"\n<p>Es com\u00fan o\u00edr, cuando alguien ha vendido su piso, los dilemas que ha tenido a la hora de pagar \u201clas plusval\u00edas\u201d. En realidad, la plusval\u00eda municipal solo se paga una vez. S\u00ed que existen, sin embargo, un par de <strong>impuestos que uno debe liquidar tras la venta de una vivienda<\/strong> (el IRPF, aparte de la plusval\u00eda), cuyas diferencias detallamos a continuaci\u00f3n para despejar cualquier duda.<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-67\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_67 module_id_67   hustle-size--custom\"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"67\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfSabes cu\u00e1nto pagar\u00e1s de plusval\u00eda municipal? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfSabes cu\u00e1nto pagar\u00e1s de plusval\u00eda municipal?<\/h3><h4 class=\"hustle-subtitle\">Obt\u00e9n en menos de 1 minuto el resultado de aplicar los dos m\u00e9todos. \u00a1Es gratis!<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/calculadora-plusvalia-municipal?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_calculadora_plusvalia_blog&#038;utm_term=calculadora_plusvalia_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">QUIERO PROBAR<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">1. La plusval\u00eda municipal<\/h2>\n\n\n\n<p>La plusval\u00eda es lo que com\u00fanmente conocemos como <strong>impuesto sobre el incremento de valor de los terrenos urbanos<\/strong>, que recolecta cada ayuntamiento durante los 30 d\u00edas h\u00e1biles posteriores a la venta de un piso.<\/p>\n\n\n\n<p>En verdad, <strong>solo debe pagarse cuando en efecto ha habido un incremento del valor del terreno<\/strong>, aunque hasta hace unos a\u00f1os los ayuntamientos lo cobraban como una suerte de impuesto sobre cualquier venta.<\/p>\n\n\n\n<p>Por esa raz\u00f3n, en 2017 <strong>el Tribunal Supremo declar\u00f3 inconstitucional determinadas normas de la regulaci\u00f3n de este impuesto<\/strong>, cuando en la venta no se hab\u00eda producido un incremento del valor de los terrenos.<\/p>\n\n\n\n<p>Desde entonces, existen <strong>dos m\u00e9todos para calcular este impuesto<\/strong>, que el contribuyente puede elegir seg\u00fan le convenga:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>El nuevo m\u00e9todo \u201cobjetivo\u201d<\/strong>, que se aplica por defecto y que toma el valor catastral del suelo y los a\u00f1os en que se ha generado el incremento.<\/li>\n\n\n\n<li><strong>El m\u00e9todo real<\/strong>, que toma el beneficio real de la venta (valor de venta menos el de compra) de la operaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>Puedes usar una <a href=\"https:\/\/housfy.com\/vender-pisos\/calculadora-plusvalia-municipal\"><strong>calculadora de plusval\u00eda municipal<\/strong><\/a> para ver qu\u00e9 m\u00e9todo te sale m\u00e1s a cuenta y cu\u00e1nto pagar\u00edas de plusval\u00eda por vender tu piso.<\/p>\n\n\n\n<p>[irp posts=\u00bb9142&#8243; name=\u00bbManual para evitar pago plusval\u00eda herencia\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. IRPF por vender un piso<\/h2>\n\n\n\n<p>Siempre que haya habido una ganancia patrimonial, habr\u00e1 que <strong>pagar el impuesto sobre la renta de las personas f\u00edsicas (IRPF)<\/strong> sobre ese beneficio. Aunque mucha gente lo confunde como una segunda \u201cplusval\u00eda\u201d, en realidad se trata de declarar la venta de tu vivienda en la declaraci\u00f3n de la renta del ejercicio correspondiente.<\/p>\n\n\n\n<p>Este 2024, la <strong>campa\u00f1a de la declaraci\u00f3n de la renta<\/strong> ya ha comenzado, por lo que, si vendiste tu piso durante 2023, es hora de rendir cuentas con Hacienda.<\/p>\n\n\n\n<p>El IRPF se paga sobre las <strong>ganancias patrimoniales<\/strong> (valor de transmisi\u00f3n \u2013 valor de adquisici\u00f3n) y es progresivo seg\u00fan los tramos del ejercicio en cuesti\u00f3n. Para 2024, son los siguientes:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><strong>Ganancias patrimoniales sujetas a tributo<\/strong><\/td><td><strong>Tipo impositivo<\/strong><\/td><\/tr><tr><td>hasta 6.000 \u20ac<\/td><td>19 %<\/td><\/tr><tr><td>entre 6.000 \u20ac y 50.000 \u20ac<\/td><td>21 %<\/td><\/tr><tr><td>entre 50.000 \u20ac y 200.000 \u20ac<\/td><td>23 %<\/td><\/tr><tr><td>entre 200.000 \u20ac y 300.000 \u20ac<\/td><td>27 %<\/td><\/tr><tr><td>a partir de 300.000 \u20ac<\/td><td>30 %<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-40\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_40 module_id_40   hustle-size--custom\"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"40\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"Vender un piso es dif\u00edcil, hasta que no lo es popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">Vender un piso es dif\u00edcil, hasta que no lo es<\/h3><h4 class=\"hustle-subtitle\">Encontramos a tu comprador ideal 3 veces m\u00e1s r\u00e1pido<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_vender_publicitario_blog&#038;utm_term=vender_publicitario_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">\u00a1ESTOY LISTO!<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Diferencias entre la plusval\u00eda y el IRPF tras vender un piso<\/h2>\n\n\n\n<p>Los dos impuestos que hay que pagar tras la venta de tu piso son <strong>la plusval\u00eda municipal y el IRPF<\/strong>: conoce las diferencias principales entre ambos en la siguiente tabla.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Plusval\u00eda municipal<\/strong><\/td><td><strong>IRPF<\/strong><\/td><\/tr><tr><td>Lo recauda el&nbsp;<strong>ayuntamiento&nbsp;<\/strong>donde est\u00e1 la vivienda<\/td><td>Lo recauda la&nbsp;<strong>Agencia Tributaria<\/strong>, en la declaraci\u00f3n de la renta y patrimonio<\/td><\/tr><tr><td>Se paga en los&nbsp;<strong>30 d\u00edas posteriores<\/strong>&nbsp;a la venta<\/td><td>Se paga al&nbsp;<strong>a\u00f1o siguiente<\/strong>&nbsp;de la venta<\/td><\/tr><tr><td>Se paga solo si ha habido un&nbsp;<strong>incremento del valor del suelo<\/strong><\/td><td>Se paga solo si ha habido una&nbsp;<strong>ganancia patrimonial<\/strong>&nbsp;con la venta<\/td><\/tr><tr><td>Existen&nbsp;<strong>dos m\u00e9todos<\/strong>&nbsp;\u2014el objetivo y el real\u2014 entre los que puedes elegir<\/td><td>Se aplican a la ganancia los&nbsp;<strong>tipos impositivos<\/strong>&nbsp;aprobados para el ejercicio<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>[irp posts=\u00bb55317&#8243; name=\u00bbComienza la declaraci\u00f3n de la renta 2024: as\u00ed es c\u00f3mo debes declarar la venta de tu piso\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A\u00fan no he vendido mi piso: \u00bfcu\u00e1nto deber\u00e9 pagar de plusval\u00eda?<\/h2>\n\n\n\n<p>Si te est\u00e1s informando porque tu idea es <a href=\"https:\/\/housfy.com\/vender-pisos\"><strong>vender tu piso pronto<\/strong><\/a>, Housfy puede ayudarte. Nuestros tiempos medios de venta son inferiores a los 60 d\u00edas y, adem\u00e1s, te asesoramos con todo lo relacionado con la operaci\u00f3n: desde la publicaci\u00f3n de tu anuncio hasta la firma de las escrituras.<\/p>\n\n\n\n<p>Adem\u00e1s, puedes calcular <strong>cu\u00e1nto pagar\u00e1s de plusval\u00eda<\/strong> con cada m\u00e9todo gracias a nuestra herramienta online y gratuita. Pru\u00e9bala ahora:<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-67\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_67 module_id_67   hustle-size--custom\"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"67\"\r\n\t\t\tdata-render-id=\"1\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfSabes cu\u00e1nto pagar\u00e1s de plusval\u00eda municipal? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfSabes cu\u00e1nto pagar\u00e1s de plusval\u00eda municipal?<\/h3><h4 class=\"hustle-subtitle\">Obt\u00e9n en menos de 1 minuto el resultado de aplicar los dos m\u00e9todos. \u00a1Es gratis!<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/vender-pisos\/calculadora-plusvalia-municipal?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_calculadora_plusvalia_blog&#038;utm_term=calculadora_plusvalia_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">QUIERO PROBAR<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es com\u00fan o\u00edr, cuando alguien ha vendido su piso, los dilemas que ha tenido a la hora de pagar \u201clas plusval\u00edas\u201d. En realidad, la plusval\u00eda municipal solo se paga una vez. S\u00ed que existen, sin embargo, un par de impuestos que uno debe liquidar tras la venta de una vivienda (el IRPF, aparte de la plusval\u00eda), cuyas diferencias detallamos a continuaci\u00f3n para despejar cualquier duda. 1. La plusval\u00eda municipal La plusval\u00eda es lo que com\u00fanmente conocemos como impuesto sobre el incremento de valor de los terrenos urbanos, que recolecta cada ayuntamiento durante los 30 d\u00edas h\u00e1biles posteriores a la venta <\/p>\n","protected":false},"author":1,"featured_media":55347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-55345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2024\/04\/02105037\/diferencias-plusvalia-irpf-vender-piso-scaled.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/55345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=55345"}],"version-history":[{"count":4,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/55345\/revisions"}],"predecessor-version":[{"id":60706,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/55345\/revisions\/60706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/55347"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=55345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=55345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=55345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}