{"id":61171,"date":"2025-04-02T08:00:00","date_gmt":"2025-04-02T08:00:00","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=61171"},"modified":"2025-04-02T11:49:36","modified_gmt":"2025-04-02T11:49:36","slug":"cambios-en-el-itp-cataluna-todo-lo-que-necesitas-saber-para-este-2025","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/cambios-en-el-itp-cataluna-todo-lo-que-necesitas-saber-para-este-2025\/","title":{"rendered":"Cambios en el ITP Catalu\u00f1a: Todo lo que necesitas saber para este 2025"},"content":{"rendered":"\n<p>El Diari Oficial de la Generalitat de Catalunya (DOGC) ha publicado el <strong>nuevo Decreto Ley<\/strong> 5\/2025, que introduce importantes <strong>cambios fiscales en el Impuesto sobre Transmisiones Patrimoniales (ITP)<\/strong> en Catalu\u00f1a, de los cuales la mayor\u00eda entrar\u00e1n en vigor el 27 de junio de 2025. Eso s\u00ed, para que se mantenga su vigencia, el Parlament deber\u00e1 convalidarlo en un m\u00e1ximo de 30 d\u00edas.<\/p>\n\n\n\n<p>Veamos en qu\u00e9 consisten estas reformas.<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-38\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_38 module_id_38   hustle-size--custom\"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"38\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfEst\u00e1s pensando en comprar un piso?  popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfEst\u00e1s pensando en comprar un piso? <\/h3><h4 class=\"hustle-subtitle\">Encuentra viviendas en venta en tu ciudad y compra la perfecta para ti <\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/venta-inmuebles?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_portalBuyers_blog&#038;utm_term=portalBuyers_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">BUSCAR PISOS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Nuevos tramos del ITP en Catalu\u00f1a e incrementos espec\u00edficos<\/h2>\n\n\n\n<p>Uno de los cambios m\u00e1s significativos es la introducci\u00f3n de <strong>nuevos tramos impositivos<\/strong> para la compra de vivienda de segunda mano. En concreto, se aumenta la tributaci\u00f3n de aquellos inmuebles con un valor superior a<strong> 600.000\u20ac<\/strong>, lo que significa que las operaciones de mayor valor pagar\u00e1n m\u00e1s impuestos.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>Asimismo, se produce un incremento del ITP al <strong>20% para los grandes tenedores y las adquisiciones de edificios enteros <\/strong>de viviendas -con o sin divisi\u00f3n horizontal-. <\/p>\n\n\n\n<p>No obstante, existen <strong>excepciones<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si el adquirente es un<strong> promotor social o una entidad sin \u00e1nimo de lucro<\/strong> que proporciona vivienda a personas en situaci\u00f3n de <strong>vulnerabilidad<\/strong>.<\/li>\n\n\n\n<li>Cuando la adquisici\u00f3n se destine a <strong>sede social o centro de trabajo<\/strong> de un gran tenedor.<\/li>\n\n\n\n<li>En el caso de adquisici\u00f3n de edificios, si:\n<ul class=\"wp-block-list\">\n<li>El comprador es una <strong>persona f\u00edsica<\/strong>.<\/li>\n\n\n\n<li>El edificio tiene un<strong> m\u00e1ximo de 4 viviendas<\/strong>.<\/li>\n\n\n\n<li>Todas las viviendas sean la <strong>residencia habitual del comprador y sus familiares<\/strong> hasta segundo grado.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Pero eso no es todo. El Decreto Ley 5\/2025<strong> elimina la bonificaci\u00f3n del 70% del ITP para empresas <\/strong>dedicadas al \u00abflipping\u00bb inmobiliario. <\/p>\n\n\n<p>[irp posts=\u00bb60746&#8243; name=\u00bb\u00a1OJO! Estas son las fechas l\u00edmite para la declaraci\u00f3n de la renta del 2024&#8243;]<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Hay bonificaciones con buenas nuevas <\/h2>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>Habr\u00e1 ciertos colectivos que a partir de junio de 2025 podr\u00e1n disfrutar de la continuaci\u00f3n de ciertas bonificaciones <strong>ya establecidas<\/strong>, y otros que inclusive lo har\u00e1n de unas <strong>nuevas<\/strong>. Estas deducciones son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La transmisi\u00f3n de viviendas de protecci\u00f3n oficial (VPO) seguir\u00e1 tributando al 7%.<\/li>\n\n\n\n<li>Las familias numerosas, monoparentales y personas con discapacidad seguir\u00e1n tributando al 5%.<\/li>\n\n\n\n<li>Se introduce un nuevo tipo reducido del 5% para v\u00edctimas de violencia machista.<\/li>\n\n\n\n<li>La bonificaci\u00f3n del 5% para la compra de vivienda habitual para j\u00f3venes se ampl\u00eda hasta los menores de 36 a\u00f1os (antes 33).<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>Se ha establecido una bonificaci\u00f3n del <strong>100% del IVA<\/strong> sobre viviendas nuevas adquiridas por j\u00f3venes <strong>menores de 36 a\u00f1os<\/strong>, eso s\u00ed, siempre que se trate de la<strong> vivienda habitual <\/strong>del comprador y la base imponible general y del ahorro en su declaraci\u00f3n de IRPF (menos el m\u00ednimo personal y familiar) no supere los <strong>36.000\u20ac<\/strong>.<\/p>\n<\/div><\/div>\n\n\n\n<p>Asimismo, se ha querido dar un empujoncito a las <strong>viviendas de protecci\u00f3n oficial<\/strong>, y se ha aprobado una bonificaci\u00f3n del <strong>50%<\/strong> de la cuota para la compra de edificios de oficinas o estructuras no finalizadas, si se transforman en viviendas de esta modalidad.<\/p>\n\n\n<p>[irp posts=\u00bb60786&#8243; name=\u00bbQu\u00e9 tipo de contrato de arras me conviene m\u00e1s al vender mi piso\u00bb]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entonces, \u00bfqu\u00e9 implicaciones tiene para los compradores y los vendedores?<\/h2>\n\n\n\n<p>Estos cambios en el ITP en Catalu\u00f1a buscan <strong>favorecer el acceso a la vivienda<\/strong> a ciertos colectivos, generalmente los m\u00e1s afectados hasta el momento, y <strong>evitar la especulaci\u00f3n y el negocio<\/strong> con uno de los derechos m\u00e1s importantes de la poblaci\u00f3n. <\/p>\n\n\n\n<p>Por tanto, si buscabas <strong><a href=\"https:\/\/housfy.com\/venta-inmuebles\">comprar una vivienda<\/a><\/strong> y formas parte de uno de los colectivos mencionados, est\u00e1 de suerte, porque si todo sigue su curso, a partir del 27 de junio podr\u00e1s aprovechar alguna, o incluso algunas, <strong>bonificaciones <\/strong>en el ITP en Catalu\u00f1a.<\/p>\n\n\n\n<p>Si, por contra pensabas en <strong><a href=\"https:\/\/housfy.com\/vender-pisos\">vender tu piso<\/a><\/strong> en la comunidad aut\u00f3noma, no te preocupes, porque tambi\u00e9n son <strong>buenas noticias<\/strong> para ti. Estas deducciones podr\u00edas beneficiar a muchas personas que hasta ahora ve\u00edan el acceso a vivienda mediante compra muy lejano, con lo cual tendr\u00e1s una <strong>demanda todav\u00eda m\u00e1s amplia<\/strong>, as\u00ed como <strong>menos competencia<\/strong> por parte de inversores.<\/p>\n\n\n\n<div\r\n\t\t\t\tid=\"hustle-embedded-id-77\"\r\n\t\t\t\tclass=\"hustle-ui hustle-inline hustle-palette--gray_slate hustle_module_id_77 module_id_77   hustle-size--custom\"\r\n\t\t\t\t\r\n\t\t\tdata-id=\"77\"\r\n\t\t\tdata-render-id=\"0\"\r\n\t\t\tdata-tracking=\"enabled\"\r\n\t\t\t\r\n\t\t\t\tdata-intro=\"no_animation\"\r\n\t\t\t\tdata-sub-type=\"shortcode\"\r\n\t\t\t\t\r\n\t\t\t\tstyle=\"opacity: 0;\"\r\n\t\t\t\taria-label=\"\u00bfBuscando tu inmobiliaria de confianza? popup\"\r\n\t\t\t><div class=\"hustle-inline-content\"><div class=\"hustle-info hustle-info--compact\"><div class=\"hustle-main-wrapper\"><div class=\"hustle-layout\"><div class=\"hustle-content\"><div class=\"hustle-content-wrap\"><div class=\"hustle-group-title\"><h3 class=\"hustle-title\">\u00bfBuscando tu inmobiliaria de confianza?<\/h3><h4 class=\"hustle-subtitle\">En Housfy seremos eso y m\u00e1s, una nueva forma de resolver tus necesidades inmobiliarias<\/h4><\/div><div class=\"hustle-cta-container\"><a class=\"hustle-button hustle-button-cta \" href=\"https:\/\/housfy.com\/inmobiliarias?utm_source=traffic_CTABanner_Embed_blog&#038;utm_medium=CTABanner&#038;utm_campaign=CTABanner_Embed_housfy_inmobiliarias&#038;utm_term=housfy_CTABanner_Embed_blog\" target=\"_blank\" data-cta-type=\"cta\">CON\u00d3CENOS<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Diari Oficial de la Generalitat de Catalunya (DOGC) ha publicado el nuevo Decreto Ley 5\/2025, que introduce importantes cambios fiscales en el Impuesto sobre Transmisiones Patrimoniales (ITP) en Catalu\u00f1a, de los cuales la mayor\u00eda entrar\u00e1n en vigor el 27 de junio de 2025. Eso s\u00ed, para que se mantenga su vigencia, el Parlament deber\u00e1 convalidarlo en un m\u00e1ximo de 30 d\u00edas. Veamos en qu\u00e9 consisten estas reformas. Nuevos tramos del ITP en Catalu\u00f1a e incrementos espec\u00edficos Uno de los cambios m\u00e1s significativos es la introducci\u00f3n de nuevos tramos impositivos para la compra de vivienda de segunda mano. En concreto, <\/p>\n","protected":false},"author":1,"featured_media":61183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133,1],"tags":[],"class_list":["post-61171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comprar-piso","category-noticias","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2025\/04\/01094021\/ITP-Cataluna.png","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/61171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=61171"}],"version-history":[{"count":4,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/61171\/revisions"}],"predecessor-version":[{"id":61185,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/61171\/revisions\/61185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/61183"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=61171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=61171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=61171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}