{"id":7988,"date":"2019-10-01T09:00:49","date_gmt":"2019-10-01T08:00:49","guid":{"rendered":"https:\/\/housfy.com\/blog\/?p=7988"},"modified":"2022-02-22T10:59:13","modified_gmt":"2022-02-22T10:59:13","slug":"personas-mayores-y-cohousing-una-nueva-forma-de-vivir-la-vejez","status":"publish","type":"post","link":"https:\/\/housfy.com\/blog\/personas-mayores-y-cohousing-una-nueva-forma-de-vivir-la-vejez\/","title":{"rendered":"Personas mayores y cohousing: una nueva forma de vivir la vejez"},"content":{"rendered":"<p>La vivienda para personas mayores un un grave problema social al que no se le est\u00e1 prestando mucha atenci\u00f3n. <strong>La soledad es uno de los mayores problemas para la gente mayor<\/strong>, muchas veces no se les puede cuidar todo lo que se quiere y nos vemos obligados a ingresarlos en una residencia. Aunque no sea la mejor soluci\u00f3n, a veces las circunstancias nos llevan a ello. Pero <strong>ahora tenemos una gran alternativa: el cohousing<\/strong>, una maravillosa iniciativa para las personas mayores.<\/p>\n<p>[irp posts=\u00bb7968&#8243; name=\u00bbTransforma tu vivienda en un plan de pensiones\u00bb]<\/p>\n<h2><span style=\"font-size: 12pt;\">\u00bfQu\u00e9 es el cohousing?<\/span><\/h2>\n<p>En el cohousing residen tanto personas mayores como j\u00f3venes, es un espacio en el que se puede vivir en viviendas independientes y se comparten las zonas comunes. Se crea un sistema de autogesti\u00f3n y cooperaci\u00f3n que es muy beneficioso para la comunidad.<\/p>\n<p>Este concepto origin\u00f3 a ra\u00edz de una necesidad: la de <strong>ayudar a las personas mayores a encontrar un sitio donde vivir tranquilamente<\/strong>. Las residencias no son un sitio donde disfrutar de la vejez, son lugares impersonales m\u00e1s parecidos a hospitales que a un hogar. Con el cohousing contar\u00e1s con tu hogar personal y tu independencia, pero adem\u00e1s podr\u00e1s disfrutar de la vida en comunidad y con un sistema de ayuda cooperativa.<\/p>\n<p>El cohousing se cre\u00f3 en los a\u00f1os 80 a ra\u00edz de la idea de unos j\u00f3venes holandeses y daneses. En Holanda y Dinamarca fueron los primeros pa\u00edses en los que surgi\u00f3 este sistema de viviendas, pero actualmente podemos encontrarlo en muchos puntos del mundo.<\/p>\n<h2><span style=\"font-size: 12pt;\">La calidad de vida de las personas mayores en el cohousing<\/span><\/h2>\n<p>Esta forma de vivir es muy beneficiosa tanto para los m\u00e1s mayores como para los j\u00f3venes que residen en la comunidad. En el cohousing <strong>se crea un sentimiento de comunidad y de ayuda mutua<\/strong>, existe una gran red de apoyo y esto aumenta la autoestima y la calidad de vida.<\/p>\n<p>La soledad no ser\u00e1 un problema, ya que se crea un gran sistema de apoyo, pero a la vez si te apetece algo de tiempo para ti mismo puedes ir a tu casa a descansar y desconectar. \u00a1Si es que pensaron en todo cuando crearon el cohousing!<\/p>\n<p>Aqu\u00ed tienes un ejemplo de lo que ser\u00eda un espacio de cohousing<\/p>\n<div id=\"attachment_7991\" style=\"width: 742px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-7991\"  class=\"wp-image-7991 size-full\" title=\"cohousing\" src=\"data:image\/gif,GIF89a%01%00%01%00%80%00%00%00%00%00%FF%FF%FF%21%F9%04%01%00%00%00%00%2C%00%00%00%00%01%00%01%00%00%02%01D%00%3B\" data-layzr=\"https:\/\/static0.housfy.com\/prod\/blog\/images\/2019\/09\/30113246\/ScreenHunter_127-Dec.-29-12.41.jpg\" alt=\"Fuente: Muhimu\" width=\"732\" height=\"421\" \/><p id=\"caption-attachment-7991\" class=\"wp-caption-text\">Fuente: muhimu<\/p><\/div>\n<h2><span style=\"font-size: 12pt;\">\u00bfD\u00f3nde podemos encontrar viviendas de cohousing para personas mayores?<\/span><\/h2>\n<p>\u00bfTe ha convencido el cohousing? Pues existen muchas regiones de Europa en el que existen este tipo de comunidades, qui\u00e9n sabe, puede que te apetezca irte a vivir a otro pa\u00eds. Pero si no es el caso, que sepas que en Espa\u00f1a hay muchas zonas en las que podremos encontrar este tipo de viviendas.<\/p>\n<h2><span style=\"font-size: 12pt;\">\u00bfCu\u00e1nto cuestan?<\/span><\/h2>\n<p>Se trata de viviendas muy asequibles ya que la mayor\u00eda de los gastos son compartidos por la comunidad: wifi, luz, agua, hipoteca e incluso el coche.<\/p>\n<p>El cohousing <strong>es una gran opci\u00f3n tanto para personas j\u00f3venes como para las personas mayores<\/strong>. Todo son ventajas: es muy asequible, mejora tu calidad de vida, hay un sistema de ayuda mutua y a la vez puedes seguir disfrutando de tu espacio personal.<\/p>\n<p>Pero en caso de que este sistema de cohousing no te haya convencido y sigues prefiriendo una casa, puedes consultar nuestra cartera de pisos donde te espera la casa de tus sue\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vivienda para personas mayores un un grave problema social al que no se le est\u00e1 prestando mucha atenci\u00f3n. La soledad es uno de los mayores problemas para la gente mayor, muchas veces no se les puede cuidar todo lo que se quiere y nos vemos obligados a ingresarlos en una residencia. Aunque no sea la mejor soluci\u00f3n, a veces las circunstancias nos llevan a ello. Pero ahora tenemos una gran alternativa: el cohousing, una maravillosa iniciativa para las personas mayores.  \u00bfQu\u00e9 es el cohousing? En el cohousing residen tanto <\/p>\n","protected":false},"author":1,"featured_media":7989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133,134],"tags":[],"class_list":["post-7988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comprar-piso","category-vender-piso","has_thumb"],"img_url":"https:\/\/static0.housfy.com\/prod\/blog\/images\/2019\/09\/30110508\/matthew-bennett-78hTqvjYMS4-unsplash.jpg","_links":{"self":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/7988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/comments?post=7988"}],"version-history":[{"count":9,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/7988\/revisions"}],"predecessor-version":[{"id":27162,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/posts\/7988\/revisions\/27162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media\/7989"}],"wp:attachment":[{"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/media?parent=7988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/categories?post=7988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housfy.com\/blog\/wp-json\/wp\/v2\/tags?post=7988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}